{"id":77615,"date":"2026-07-16T09:25:40","date_gmt":"2026-07-16T09:25:40","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=77615"},"modified":"2026-07-16T09:25:42","modified_gmt":"2026-07-16T09:25:42","slug":"votacao-do-estatuto-do-aprendiz-e-adiada-apos-pedidos-de-vista-na-cas","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/07\/16\/votacao-do-estatuto-do-aprendiz-e-adiada-apos-pedidos-de-vista-na-cas\/","title":{"rendered":"Vota\u00e7\u00e3o do Estatuto do Aprendiz \u00e9 adiada ap\u00f3s pedidos de vista na CAS"},"content":{"rendered":"\n<p>Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/p>\n\n\n\n<p>A Comiss\u00e3o de Assuntos Sociais (CAS) do Senado adiou a vota\u00e7\u00e3o do projeto que cria o Estatuto do Aprendiz (PL 6461\/2019), projeto que, se aprovado, estabelecer\u00e1 regras para a jornada de trabalho e direitos do aprendiz, bem como situa\u00e7\u00f5es relativas \u00e0 rescis\u00e3o do contrato de trabalho.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1696755&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1696755&amp;o=node\"><\/p>\n\n\n\n<p>O adiamento da vota\u00e7\u00e3o se deve ao pedido de vista feito, nesta quarta-feira (15), pelos senadores Jaime Bagattoli (PL-RO), La\u00e9rcio Oliveira (PP-SE) e Marcos Pontes (PL-SP).<\/p>\n\n\n\n<p>Com isso, a <strong>delibera\u00e7\u00e3o sobre o parecer ficou suspensa e o projeto dever\u00e1 voltar \u00e0 pauta da comiss\u00e3o provavelmente na pr\u00f3xima reuni\u00e3o, segundo o presidente da CAS, senador Marcelo Castro (MDB-PI).<\/strong><\/p>\n\n\n\n<p><strong>Aprovado em abril pela C\u00e2mara dos Deputados, o PL 6.461\/2019 tem, como p\u00fablico-alvo priorit\u00e1rio, jovens de 14 a 24 anos e pessoas com defici\u00eancia. <\/strong>Ele estabelece regras para a jornada de trabalho que visam preservar a caracter\u00edstica de aprendizagem nos contratos de aprendizagem.<\/p>\n\n\n\n<p>Para tanto, o texto origin\u00e1rio altera alguns dispositivos da Consolida\u00e7\u00e3o das Leis do Trabalho (CLT) e de outras leis relacionadas \u00e0 aprendizagem profissional de jovens e pessoas com defici\u00eancia.<\/p>\n\n\n\n<p><strong>No Senado, o projeto tem, como relator, o senador Veneziano Vital do R\u00eago (MDB-PB). Segundo ele, o estatuto contribuir\u00e1 para uma reorganiza\u00e7\u00e3o de normas que atualmente encontram-se dispersas na legisla\u00e7\u00e3o do pa\u00eds.<\/strong><\/p>\n\n\n\n<p><strong>O texto estimula a forma\u00e7\u00e3o de m\u00e3o de obra qualificada e favorece a perman\u00eancia dos jovens na escola, segundo Veneziano.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Direitos, deveres e inclus\u00e3o<\/h2>\n\n\n\n<p>O projeto foi apresentado com o prop\u00f3sito de incentivar a contrata\u00e7\u00e3o de aprendizes, definindo direitos e deveres dos participantes dos programas de aprendizagem, favorecendo a inclus\u00e3o social e profissional de seu p\u00fablico.<\/p>\n\n\n\n<p><strong>Atualmente, a legisla\u00e7\u00e3o determina que as empresas enquadradas na cota de aprendizagem devem ter entre 5% e 15% de seu quadro (de trabalhadores que exercem fun\u00e7\u00f5es que demandem forma\u00e7\u00e3o profissional) composto por aprendizes.<\/strong><\/p>\n\n\n\n<p>O projeto do Estatuto do Aprendiz mant\u00e9m essa l\u00f3gica, mas amplia as hip\u00f3teses em que a contrata\u00e7\u00e3o poder\u00e1 ser facultativa.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contrata\u00e7\u00e3o facultativa<\/h2>\n\n\n\n<p>O texto prev\u00ea que ser\u00e1 facultativa a contrata\u00e7\u00e3o de aprendizes nos seguintes casos:<\/p>\n\n\n\n<p>&#8211; se desejarem, estabelecimentos com menos de sete empregados poder\u00e3o contratar um aprendiz;<\/p>\n\n\n\n<p>&#8211; microempresas e empresas de pequeno porte, inclusive as optantes pelo Simples Nacional;<\/p>\n\n\n\n<p>&#8211; entidades sem fins lucrativos que tenham por objetivo a educa\u00e7\u00e3o profissional e tenham habilita\u00e7\u00e3o na modalidade aprendizagem profissional com turma de aprendizagem profissional em andamento;<\/p>\n\n\n\n<p>&#8211; empresas cuja atividade principal seja de teleatendimento ou telemarketing se ao menos 40% de seus empregados tenham at\u00e9 24 anos, conforme regulamento;<\/p>\n\n\n\n<p>&#8211; \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o p\u00fablica direta, aut\u00e1rquica e fundacional de entes federativos que adotem regime estatut\u00e1rio para seus servidores p\u00fablicos; e<\/p>\n\n\n\n<p>&#8211; empregador rural pessoa f\u00edsica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Outros pontos<\/h2>\n\n\n\n<p>O texto enviado pela C\u00e2mara ao Senado deixa expl\u00edcitos v\u00e1rios direitos dos aprendizes aplicados aos contratados pela CLT.<\/p>\n\n\n\n<p><strong>Al\u00e9m do vale-transporte, o texto assegura \u00e0 aprendiz gestante o direito \u00e0 garantia provis\u00f3ria do emprego desde a confirma\u00e7\u00e3o da gravidez at\u00e9 cinco meses ap\u00f3s o parto.<\/strong><\/p>\n\n\n\n<p>Durante o per\u00edodo da licen\u00e7a, a aprendiz deve se afastar de suas atividades, com garantia do retorno ao mesmo programa de aprendizagem caso ainda esteja em andamento.<\/p>\n\n\n\n<p>A certifica\u00e7\u00e3o do aproveitamento dever\u00e1 ser por unidades curriculares, m\u00f3dulos ou etapas conclu\u00eddas.<\/p>\n\n\n\n<p>Caso o prazo original do contrato se encerre durante a garantia provis\u00f3ria, ele dever\u00e1 ser prorrogado at\u00e9 o \u00faltimo dia dessa garantia, mantendo as condi\u00e7\u00f5es originais, como jornada e hor\u00e1rio de trabalho, fun\u00e7\u00e3o e sal\u00e1rio.<\/p>\n\n\n\n<p>Os encargos devem continuar sendo recolhidos. S\u00f3 ser\u00e3o permitidas altera\u00e7\u00f5es que sejam em benef\u00edcio do aprendiz.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contratantes<\/h2>\n\n\n\n<p><strong>O estabelecimento que contratar o aprendiz ter\u00e1 de matricul\u00e1-lo em curso de aprendizagem profissional correspondente \u00e0 ocupa\u00e7\u00e3o escolhida, preferencialmente nos servi\u00e7os nacionais de aprendizagem do Sistema S.<\/strong><\/p>\n\n\n\n<p>No caso de o Sistema S n\u00e3o oferecer vaga suficiente para atender \u00e0 demanda, a matr\u00edcula poder\u00e1 ser feita em institui\u00e7\u00f5es p\u00fablicas federais, estaduais, municipais e distritais de ensino profissional t\u00e9cnico de n\u00edvel m\u00e9dio.<\/p>\n\n\n\n<p>Poder\u00e1 ser feita tamb\u00e9m em entidades de pr\u00e1tica desportiva filiadas ao Sistema Nacional do Desporto ou em entidades sem fins lucrativos voltadas \u00e0 presta\u00e7\u00e3o de assist\u00eancia ao adolescente e \u00e0 educa\u00e7\u00e3o profissional. Essas entidades precisam estar registradas no conselho municipal dos direitos da crian\u00e7a e do adolescente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acidente de trabalho; f\u00e9rias<\/h2>\n\n\n\n<p>Caso o aprendiz venha a sofrer acidente de trabalho, ele ter\u00e1 garantida a manuten\u00e7\u00e3o do emprego pelo prazo de 12 meses, contados a partir do fim do pagamento do aux\u00edlio, aplicando-se regras de adapta\u00e7\u00e3o semelhantes \u00e0s da aprendiz gr\u00e1vida.<\/p>\n\n\n\n<p><strong>As f\u00e9rias dever\u00e3o ser concedidas coincidentemente ao per\u00edodo de f\u00e9rias escolares aos aprendizes menores de 18 anos \u2013 podendo, inclusive, ser parceladas, desde que a crit\u00e9rio do aprendiz.<\/strong><\/p>\n\n\n\n<p>No caso de f\u00e9rias coletivas em per\u00edodos n\u00e3o coincidentes com as escolares ou as estabelecidas em programa de aprendizagem, a empresa poder\u00e1 dispensar o aprendiz de comparecer ao servi\u00e7o, desde que sem preju\u00edzo do sal\u00e1rio e das f\u00e9rias normais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bolsa fam\u00edlia; servi\u00e7o militar<\/h2>\n\n\n\n<p>O rendimento recebido pelo aprendiz durante o per\u00edodo do contrato ficar\u00e1 de fora do c\u00e1lculo de renda familiar m\u00e9dia mensal para acesso ao benef\u00edcio do programa Bolsa fam\u00edlia.<\/p>\n\n\n\n<p><strong>Caso o aprendiz tenha de ser afastado por conta do servi\u00e7o militar obrigat\u00f3rio \u2013 ou outro encargo p\u00fablico como, por exemplo, participa\u00e7\u00e3o em j\u00fari \u2013, o per\u00edodo no servi\u00e7o n\u00e3o dever\u00e1 ser contado no prazo de dura\u00e7\u00e3o do contrato de aprendizagem.<\/strong><\/p>\n\n\n\n<p>Nesse caso, o que deve haver \u00e9 um acordo entre as partes interessadas, bem como reposi\u00e7\u00e3o das atividades te\u00f3ricas do curso de aprendizagem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Marcelo Camargo\/Ag\u00eancia Brasil A Comiss\u00e3o de Assuntos Sociais (CAS) do Senado adiou a vota\u00e7\u00e3o do projeto que cria o Estatuto do Aprendiz (PL 6461\/2019), projeto que, se aprovado, estabelecer\u00e1 regras para a jornada de trabalho e direitos do aprendiz, bem como situa\u00e7\u00f5es relativas \u00e0 rescis\u00e3o do contrato de trabalho. O adiamento da vota\u00e7\u00e3o se<\/p>\n","protected":false},"author":5,"featured_media":77616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-77615","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=77615"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77615\/revisions"}],"predecessor-version":[{"id":77617,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/77615\/revisions\/77617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/77616"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=77615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=77615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=77615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}