{"id":76121,"date":"2026-05-13T18:12:33","date_gmt":"2026-05-13T18:12:33","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=76121"},"modified":"2026-05-13T18:12:34","modified_gmt":"2026-05-13T18:12:34","slug":"mcmv-prefeitura-publica-lista-definitiva-de-contemplados-e-convoca-para-vistoria-do-residencial-verdes-horizontes-ii","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/05\/13\/mcmv-prefeitura-publica-lista-definitiva-de-contemplados-e-convoca-para-vistoria-do-residencial-verdes-horizontes-ii\/","title":{"rendered":"MCMV: Prefeitura publica lista definitiva de contemplados e convoca para vistoria do Residencial Verdes Horizontes II"},"content":{"rendered":"\n<p>A Prefeitura de Cama\u00e7ari, atrav\u00e9s da Secretaria de Habita\u00e7\u00e3o (Sehab), torna p\u00fablica a lista definitiva dos contemplados para o Residencial Verdes Horizontes II, empreendimento do programa federal Minha Casa, Minha Vida (MCMV) localizado na Avenida Industrial Urbana, bairro Ponto Certo. Com a publica\u00e7\u00e3o, os benefici\u00e1rios foram convocados para a vistoria dos apartamentos que ocorrer\u00e1 nesta ter\u00e7a-feira (12), das 9h \u00e0s 13h.<\/p>\n\n\n\n<p>Os nomes dos beneficiados constam no Di\u00e1rio Oficial do Munic\u00edpio (DOM) n.\u00ba 2864, desta segunda-feira (11). O residencial conta com 192 apartamentos, do tipo dois quartos, destinados \u00e0s fam\u00edlias selecionadas conforme os crit\u00e9rios definidos pela Caixa Econ\u00f4mica Federal e pelo Minist\u00e9rio das Cidades.<\/p>\n\n\n\n<p>A etapa de vistoria antecede a entrega oficial dos im\u00f3veis, prevista para acontecer ainda esta semana. A lista definitiva pode ser conferida neste link.<\/p>\n\n\n<p>[https:\/\/www.camacari.ba.gov.br\/wp-content\/uploads\/2026\/05\/diario-2864.certificado-2.pdf]<\/p>\n\n\n\n<p>Foto: Patrick Abreu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cama\u00e7ari, atrav\u00e9s da Secretaria de Habita\u00e7\u00e3o (Sehab), torna p\u00fablica a lista definitiva dos contemplados para o Residencial Verdes Horizontes II, empreendimento do programa federal Minha Casa, Minha Vida (MCMV) localizado na Avenida Industrial Urbana, bairro Ponto Certo. Com a publica\u00e7\u00e3o, os benefici\u00e1rios foram convocados para a vistoria dos apartamentos que ocorrer\u00e1 nesta<\/p>\n","protected":false},"author":5,"featured_media":76122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-76121","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-camacari"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/76121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=76121"}],"version-history":[{"count":2,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/76121\/revisions"}],"predecessor-version":[{"id":76124,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/76121\/revisions\/76124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/76122"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=76121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=76121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=76121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}