{"id":73097,"date":"2026-02-06T01:48:18","date_gmt":"2026-02-06T01:48:18","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=73097"},"modified":"2026-02-06T01:49:01","modified_gmt":"2026-02-06T01:49:01","slug":"numero-de-estudantes-baianos-aprovados-no-prouni-cresce-28","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/02\/06\/numero-de-estudantes-baianos-aprovados-no-prouni-cresce-28\/","title":{"rendered":"N\u00famero de estudantes baianos aprovados no Prouni cresce 28%"},"content":{"rendered":"\n<p><strong>Foto: Divulga\u00e7\u00e3o\/Ascom<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>A Bahia continua em destaque no cen\u00e1rio nacional da Educa\u00e7\u00e3o. O Estado manteve a terceira posi\u00e7\u00e3o no ranking de candidatos pr\u00e9-selecionados na primeira chamada do Programa Universidade para Todos (Prouni), que ofertas bolsas de estudos para estudantes de cursos superiores privados. A Bahia ficou atr\u00e1s apenas de Minas Gerais e S\u00e3o Paulo. Ao todo, 19.122 estudantes baianos foram pr\u00e9-selecionados, o que significa um aumento de 28,7% em compara\u00e7\u00e3o aos 14.862 aprovados do ano passado. A procura pelo programa tamb\u00e9m cresceu, tendo registrado 73.062 inscri\u00e7\u00f5es, uma alta de 6,9% em rela\u00e7\u00e3o aos 68.287 inscritos em 2025. A lista de aprovados para o primeiro semestre de 2026 foi divulgada pelo Minist\u00e9rio da Educa\u00e7\u00e3o, nesta ter\u00e7a-feira (3).<br><br>A edi\u00e7\u00e3o de 2026 do Prouni \u00e9 a maior de seus 21 anos de hist\u00f3ria. Ao todo, foram ofertadas 48.762 bolsas no Estado da Bahia, sendo 20.106 integrais (de 100% do valor do curso) e 28.656 parciais (de 50%). O n\u00famero representa um salto de 160% em rela\u00e7\u00e3o ao ano anterior, quando a oferta total foi de 18.742 &nbsp;(11.122 integrais e 7.620 parciais). Com os resultados, o programa do governo federal se consolida como uma ferramenta fundamental para o ingresso de alunos da rede p\u00fablica em institui\u00e7\u00f5es privadas de Ensino Superior, garantindo a continuidade dos estudos e a qualifica\u00e7\u00e3o profissional.<br><br><strong>Comemora\u00e7\u00f5es<br><\/strong><br>Estudantes da rede estadual de ensino celebraram a aprova\u00e7\u00e3o no Programa Universidade Para Todos. Jo\u00e3o Pedro Ferreira Santos, do Col\u00e9gio Estadual de Tempo Integral Ant\u00f4nio Felipe Evangelista Neto, no munic\u00edpio de Mutu\u00edpe, &nbsp;realizou o sonho de ser aprovado para o curso de Rela\u00e7\u00f5es Internacionais na Universidade Jorge Amado (Unijorge), em Salvador. &#8220;Tive a oportunidade de conhecer um dos segmentos das Rela\u00e7\u00f5es Internacionais na edi\u00e7\u00e3o de 2025 da Bahia Model United Nations (BaMUN, projeto da Secretaria da Educa\u00e7\u00e3o da Bahia que simula uma assembleia da ONU). Fiquei muito feliz quando vi que passei em primeiro lugar pelo Prouni para este curso&#8221;, contou.<br><br>J\u00e1 Alice Campos, do Col\u00e9gio Estadual Democr\u00e1tico Professor R\u00f4mulo Galv\u00e3o, na cidade de El\u00edsio Medrado, foi pr\u00e9-selecionada com bolsas parciais para os cursos de Biomedicina e Odontologia, na Pontif\u00edcia Universidade Cat\u00f3lica do Paran\u00e1 (PUC-PR). &#8220;\u00c9 muito gratificante ver tudo isso acontecer. Ser aprovada na PUC tamb\u00e9m \u00e9 motivo de muito orgulho para mim e para minha fam\u00edlia, tendo em vista que se trata de uma universidade privada muito renomada no cen\u00e1rio nacional&#8221;, disse.<br><br><strong>Prazos<br><\/strong><br>Os estudantes pr\u00e9-selecionados nesta etapa precisam apresentar a documenta\u00e7\u00e3o exigida na institui\u00e7\u00e3o de ensino at\u00e9 o dia 13 de fevereiro. As regras sobre a documenta\u00e7\u00e3o e modalidades de entrega variam de acordo com a institui\u00e7\u00e3o escolhida.<br><br>A segunda chamada do Prouni ser\u00e1 divulgada no dia 2 de mar\u00e7o. O per\u00edodo de comprova\u00e7\u00e3o de informa\u00e7\u00f5es acontece de 2 a 13 de mar\u00e7o. J\u00e1 os alunos que n\u00e3o foram selecionados e quiserem participar da lista de espera devem manifestar interesse pelo Portal \u00danico (<a href=\"http:\/\/acessounico.mec.gov.br\/prouni\" target=\"_blank\" rel=\"noreferrer noopener\">acessounico.mec.gov.br\/prouni<\/a>), nos dias 25 e 26 de mar\u00e7o.<br><br><strong>Sobre o Prouni<\/strong><br><br>Criado em 2004 pelo Governo Federal, o Prouni oferece bolsas de estudo em institui\u00e7\u00f5es privadas. As bolsas integrais cobrem 100% do valor do curso, enquanto as parciais custeiam 50% da mensalidade.<br><br>As inscri\u00e7\u00f5es s\u00e3o abertas a cada semestre e a sele\u00e7\u00e3o dos participantes \u00e9 feita com base na nota de uma das duas \u00faltimas edi\u00e7\u00f5es do Exame Nacional do Ensino M\u00e9dio (Enem). O programa \u00e9 direcionado para estudantes que ainda n\u00e3o t\u00eam diploma de n\u00edvel superior e que comprovem a renda exigida para cada modalidade de bolsa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Divulga\u00e7\u00e3o\/Ascom A Bahia continua em destaque no cen\u00e1rio nacional da Educa\u00e7\u00e3o. O Estado manteve a terceira posi\u00e7\u00e3o no ranking de candidatos pr\u00e9-selecionados na primeira chamada do Programa Universidade para Todos (Prouni), que ofertas bolsas de estudos para estudantes de cursos superiores privados. A Bahia ficou atr\u00e1s apenas de Minas Gerais e S\u00e3o Paulo. Ao<\/p>\n","protected":false},"author":5,"featured_media":73098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-73097","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/73097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=73097"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/73097\/revisions"}],"predecessor-version":[{"id":73099,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/73097\/revisions\/73099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/73098"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=73097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=73097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=73097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}