{"id":72483,"date":"2026-01-19T09:48:22","date_gmt":"2026-01-19T09:48:22","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=72483"},"modified":"2026-01-19T09:48:23","modified_gmt":"2026-01-19T09:48:23","slug":"mutirao-promove-servicos-de-limpeza-no-verdes-horizontes","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/01\/19\/mutirao-promove-servicos-de-limpeza-no-verdes-horizontes\/","title":{"rendered":"Mutir\u00e3o promove servi\u00e7os de limpeza no Verdes Horizontes"},"content":{"rendered":"\n<p>Como parte das a\u00e7\u00f5es para manuten\u00e7\u00e3o da limpeza e cuidado cont\u00ednuo da cidade, a Secretaria de Servi\u00e7os P\u00fablicos de Cama\u00e7ari (Sesp) realizou esta semana um mutir\u00e3o no bairro Verdes Horizontes, nas imedia\u00e7\u00f5es da linha f\u00e9rrea. Entre os servi\u00e7os executados est\u00e3o ro\u00e7agem, podas, varri\u00e7\u00e3o e retirada de entulhos.<\/p>\n\n\n\n<p>Foram contempladas as ruas da Linha, Ondina, Jardim de Al\u00e1, do Cors\u00e1rio, Stella Maris, Cabu\u00e7u, Inema, K, Amaralina, Itamaraju, Rua E Quadra V, Igarap\u00e9 e Ondina. A iniciativa contou com atua\u00e7\u00e3o de quatro equipes de trabalho, al\u00e9m do apoio de fiscais e educadores ambientais, bem como a utiliza\u00e7\u00e3o de maquin\u00e1rio e ca\u00e7ambas.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o visa promover mais conforto, seguran\u00e7a, sa\u00fade e qualidade de vida&nbsp;\u00e0&nbsp;popula\u00e7\u00e3o, refor\u00e7ando&nbsp;o&nbsp;cuidado com o espa\u00e7o p\u00fablico. Ao longo dos pr\u00f3ximos dias, equipes da Sesp seguir\u00e3o atendendo outros bairros do munic\u00edpio&nbsp;com a&nbsp;opera\u00e7\u00e3o de limpeza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte das a\u00e7\u00f5es para manuten\u00e7\u00e3o da limpeza e cuidado cont\u00ednuo da cidade, a Secretaria de Servi\u00e7os P\u00fablicos de Cama\u00e7ari (Sesp) realizou esta semana um mutir\u00e3o no bairro Verdes Horizontes, nas imedia\u00e7\u00f5es da linha f\u00e9rrea. Entre os servi\u00e7os executados est\u00e3o ro\u00e7agem, podas, varri\u00e7\u00e3o e retirada de entulhos. Foram contempladas as ruas da Linha, Ondina, Jardim<\/p>\n","protected":false},"author":5,"featured_media":72484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-72483","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-camacari"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=72483"}],"version-history":[{"count":2,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72483\/revisions"}],"predecessor-version":[{"id":72486,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/72483\/revisions\/72486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/72484"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=72483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=72483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=72483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}