{"id":71962,"date":"2026-01-07T10:41:02","date_gmt":"2026-01-07T10:41:02","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=71962"},"modified":"2026-01-07T10:41:03","modified_gmt":"2026-01-07T10:41:03","slug":"o-que-esta-em-jogo-no-cerco-do-stf-e-do-tcu-ao-banco-central-no-caso-master","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/01\/07\/o-que-esta-em-jogo-no-cerco-do-stf-e-do-tcu-ao-banco-central-no-caso-master\/","title":{"rendered":"O que est\u00e1 em jogo no cerco do STF e do TCU ao Banco Central no caso Master"},"content":{"rendered":"\n<p><strong><strong>Foto: REUTERS\/Adriano Machado<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Por Alvaro Gribel, do Estad\u00e3o<\/p>\n\n\n\n<p>O Banco Central vive um verdadeiro cerco sobre a sua atua\u00e7\u00e3o na liquida\u00e7\u00e3o do Banco Master, ocorrida em novembro do ano passado, e teme agora uma revers\u00e3o do caso.<\/p>\n\n\n\n<p>De um lado, est\u00e1 o ministro Dias Toffoli, do Supremo Tribunal Federal (STF), que decretou sigilo sobre as investiga\u00e7\u00f5es e chegou a determinar uma acarea\u00e7\u00e3o entre o banqueiro Daniel Vorcaro, dono do Master e que chegou a ser preso, e um dos diretores do BC. De outro, est\u00e1 o ministro Jonathan de Jesus, do Tribunal de Contas da Uni\u00e3o (TCU), que ordenou uma inspe\u00e7\u00e3o na autarquia para averiguar o processo de an\u00e1lise do Master.<\/p>\n\n\n\n<p>Em meio aos questionamentos do STF e do TCU, h\u00e1 um sil\u00eancio por parte da equipe econ\u00f4mica e de integrantes do governo Lula, que ainda n\u00e3o deram declara\u00e7\u00f5es de apoio ao presidente do Banco Central, Gabriel Gal\u00edpolo, e ao diretor de fiscaliza\u00e7\u00e3o, Ailton de Aquino. Ambos foram indicados para os cargos pelo presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n\n\n\n<p>Economistas e especialistas estranham as medidas adotadas pelos ministros porque consideram que n\u00e3o \u00e9 papel do STF nem do TCU fazer uma revis\u00e3o do trabalho do Banco Central. Tamb\u00e9m chama a aten\u00e7\u00e3o a rapidez com que isso vem acontecendo em pleno recesso do Poder Judici\u00e1rio e do pr\u00f3prio Tribunal de Contas.<\/p>\n\n\n\n<p>No BC, as a\u00e7\u00f5es s\u00e3o recebidas com surpresa porque nunca houve uma movimenta\u00e7\u00e3o t\u00e3o grande de ambas as cortes em processos do tipo. Nem mesmo ap\u00f3s o Programa de Est\u00edmulo \u00e0 Reestrutura\u00e7\u00e3o e ao Fortalecimento do Sistema Financeiro Nacional (Proer), quando diversos bancos privados e estatais foram liquidados, com o controle da infla\u00e7\u00e3o, algo semelhante aconteceu.<\/p>\n\n\n\n<p>Em entrevista ao Estad\u00e3o, o ex-presidente do Banco Central Arminio Fraga lembrou que, no Proer, tr\u00eas bancos privados foram liquidados, e os donos deles eram pessoas pr\u00f3ximas do ent\u00e3o presidente Fernando Henrique Cardoso. Mesmo assim, n\u00e3o houve interfer\u00eancias do STF e do TCU no caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: REUTERS\/Adriano Machado Por Alvaro Gribel, do Estad\u00e3o O Banco Central vive um verdadeiro cerco sobre a sua atua\u00e7\u00e3o na liquida\u00e7\u00e3o do Banco Master, ocorrida em novembro do ano passado, e teme agora uma revers\u00e3o do caso. De um lado, est\u00e1 o ministro Dias Toffoli, do Supremo Tribunal Federal (STF), que decretou sigilo sobre as<\/p>\n","protected":false},"author":5,"featured_media":71963,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-71962","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71962"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71962\/revisions"}],"predecessor-version":[{"id":71964,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71962\/revisions\/71964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/71963"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}