{"id":71921,"date":"2026-01-06T10:04:48","date_gmt":"2026-01-06T10:04:48","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=71921"},"modified":"2026-01-06T10:04:49","modified_gmt":"2026-01-06T10:04:49","slug":"dolar-cai-para-r-540-apos-invasao-a-venezuela","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2026\/01\/06\/dolar-cai-para-r-540-apos-invasao-a-venezuela\/","title":{"rendered":"D\u00f3lar cai para R$ 5,40 ap\u00f3s invas\u00e3o \u00e0 Venezuela"},"content":{"rendered":"\n<p>Foto: Valter Campanato\/Ag\u00eancia Brasil<\/p>\n\n\n\n<p>Apesar das tens\u00f5es com a invas\u00e3o da Venezuela e o sequestro de Nicol\u00e1s Maduro, o mercado financeiro teve um dia de al\u00edvio. O d\u00f3lar caiu para o menor valor em 25 dias. A bolsa de valores subiu e atingiu o maior n\u00edvel desde a metade de dezembro.<\/p>\n\n\n\n<p>O d\u00f3lar comercial encerrou esta segunda-feira (5) vendido a R$ 5,405, com queda de R$ 0,018 (-0,84%). A cota\u00e7\u00e3o iniciou o dia em alta, chegando a R$ 5,45 por volta das 10h30, mas inverteu a trajet\u00f3ria e passou a cair, acompanhando o movimento internacional.<\/p>\n\n\n\n<p>A moeda estadunidense est\u00e1 no menor valor desde 12 de dezembro. Na ocasi\u00e3o, a divisa fechou em R$ 5,41.<\/p>\n\n\n\n<p>No mercado de a\u00e7\u00f5es, o dia tamb\u00e9m foi marcado pelo otimismo. O \u00edndice Ibovespa, da B3, fechou a segunda aos 161.870 pontos, com alta de 0,83%. O indicador alternou altas e baixas durante a manh\u00e3, mas firmou a tend\u00eancia de alta \u00e0 tarde.<\/p>\n\n\n\n<p>A bolsa brasileira est\u00e1 no patamar mais alto desde 15 de dezembro. A\u00e7\u00f5es de bancos e de mineradoras impulsionaram o Ibovespa nesta segunda.<\/p>\n\n\n\n<p>Ap\u00f3s um in\u00edcio de preg\u00e3o tenso no mercado global, prevaleceu a leitura de que a invas\u00e3o da Venezuela deve ter um efeito deflacion\u00e1rio nos Estados Unidos. Isso porque o aumento da produ\u00e7\u00e3o de petr\u00f3leo deve elevar a oferta nos pr\u00f3ximos meses, provocando a queda do pre\u00e7o dos combust\u00edveis no mercado estadunidense no m\u00e9dio prazo.<\/p>\n\n\n\n<p>O barateamento dos combust\u00edveis reduz a press\u00e3o sobre a infla\u00e7\u00e3o nos Estados Unidos, abrindo espa\u00e7o para que o Federal Reserve (Fed, Banco Central estadunidense) corte os juros no in\u00edcio de 2026. Juros mais baixos em economias avan\u00e7adas estimulam a migra\u00e7\u00e3o de capitais para pa\u00edses emergentes, como o Brasil.<\/p>\n\n\n\n<p>*Com informa\u00e7\u00f5es da Reuters<br>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Valter Campanato\/Ag\u00eancia Brasil Apesar das tens\u00f5es com a invas\u00e3o da Venezuela e o sequestro de Nicol\u00e1s Maduro, o mercado financeiro teve um dia de al\u00edvio. O d\u00f3lar caiu para o menor valor em 25 dias. A bolsa de valores subiu e atingiu o maior n\u00edvel desde a metade de dezembro. O d\u00f3lar comercial encerrou<\/p>\n","protected":false},"author":5,"featured_media":71922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-71921","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71921"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71921\/revisions"}],"predecessor-version":[{"id":71923,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71921\/revisions\/71923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/71922"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}