{"id":71703,"date":"2025-12-31T10:39:07","date_gmt":"2025-12-31T10:39:07","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=71703"},"modified":"2025-12-31T10:39:07","modified_gmt":"2025-12-31T10:39:07","slug":"dolar-teve-queda-de-10-em-2025","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/12\/31\/dolar-teve-queda-de-10-em-2025\/","title":{"rendered":"D\u00f3lar teve queda de 10% em 2025"},"content":{"rendered":"\n<p>Foto: Valter Campanato\/Ag\u00eancia Brasil<\/p>\n\n\n\n<p>O ano de 2025 foi marcado por uma forte desvaloriza\u00e7\u00e3o do d\u00f3lar no mundo. No Brasil, a moeda norte-americana caiu 10,29% frente ao real no acumulado at\u00e9 o preg\u00e3o desta segunda-feira (29), o pen\u00faltimo do ano. Trata-se do maior recuo em quase 10 anos: em 2016, a queda foi de 17,8%.<br><\/p>\n\n\n\n<p>Neste ano, o Brasil n\u00e3o foi o \u00fanico beneficiado. Moedas de outros pa\u00edses emergentes e tamb\u00e9m de economias avan\u00e7adas \u2014 como euro, franco su\u00ed\u00e7o, iene japon\u00eas e libra esterlina \u2014 tamb\u00e9m se valorizaram frente ao d\u00f3lar.<\/p>\n\n\n\n<p>A seguir, veja os principais fatores que explicam a queda do d\u00f3lar ao longo de 2025.<\/p>\n\n\n\n<p>Pol\u00edticas de Trump<\/p>\n\n\n\n<p>Segundo especialistas consultados pelo g1, a desvaloriza\u00e7\u00e3o global do d\u00f3lar reflete, em grande parte, as pol\u00edticas adotadas pelo presidente dos Estados Unidos, Donald Trump.<\/p>\n\n\n\n<p>Ap\u00f3s a elei\u00e7\u00e3o nos EUA, o mercado financeiro esperava uma agenda conservadora e protecionista logo no in\u00edcio do mandato. A aposta era de que o republicano adotaria medidas como aumento de tarifas e corte de impostos j\u00e1 em janeiro, o que acabou n\u00e3o se confirmando.<\/p>\n\n\n\n<p>Assim, a moeda norte-americana \u2014 que iniciou 2025 cotada a R$ 6,16 \u2014 perdeu for\u00e7a ao longo dos meses e acumulou desvaloriza\u00e7\u00e3o de 7,4% ao fim do primeiro trimestre, na compara\u00e7\u00e3o com o in\u00edcio de janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Valter Campanato\/Ag\u00eancia Brasil O ano de 2025 foi marcado por uma forte desvaloriza\u00e7\u00e3o do d\u00f3lar no mundo. No Brasil, a moeda norte-americana caiu 10,29% frente ao real no acumulado at\u00e9 o preg\u00e3o desta segunda-feira (29), o pen\u00faltimo do ano. Trata-se do maior recuo em quase 10 anos: em 2016, a queda foi de 17,8%.<\/p>\n","protected":false},"author":5,"featured_media":71704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-71703","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71703"}],"version-history":[{"count":2,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71703\/revisions"}],"predecessor-version":[{"id":71706,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71703\/revisions\/71706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/71704"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}