{"id":71682,"date":"2025-12-30T10:35:36","date_gmt":"2025-12-30T10:35:36","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=71682"},"modified":"2025-12-30T10:35:37","modified_gmt":"2025-12-30T10:35:37","slug":"inscricoes-para-o-sisu-2026-comecam-em-19-de-janeiro-2","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/12\/30\/inscricoes-para-o-sisu-2026-comecam-em-19-de-janeiro-2\/","title":{"rendered":"Inscri\u00e7\u00f5es para o Sisu 2026 come\u00e7am em 19 de janeiro"},"content":{"rendered":"\n<p>Foto: Juca Varella \/ Ag\u00eancia Brasil<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es para a edi\u00e7\u00e3o do Sistema de Sele\u00e7\u00e3o Unificada (Sisu) 2026 come\u00e7ar\u00e3o no dia 19 de janeiro e poder\u00e3o ser feitas exclusivamente pela internet, at\u00e9 o dia 23 de janeiro. A edi\u00e7\u00e3o ser\u00e1 a maior em n\u00famero de institui\u00e7\u00f5es participantes, com 136 universidades, institutos federais e centros federais de educa\u00e7\u00e3o tecnol\u00f3gica, que ofertar\u00e3o 274,8 mil vagas em 7.388 cursos.<\/p>\n\n\n\n<p>A inscri\u00e7\u00e3o \u00e9 gratuita e pode ser feita exclusivamente pelo Portal de Acesso \u00danico ao Ensino Superior. Os candidatos poder\u00e3o se inscrever em at\u00e9 duas op\u00e7\u00f5es de vagas.<\/p>\n\n\n\n<p>O candidato poder\u00e1 concorrer \u00e0s modalidades de reserva de vagas da Lei de Cotas e \u00e0s a\u00e7\u00f5es afirmativas pr\u00f3prias das institui\u00e7\u00f5es. Para isso, precisa preencher o cadastro socioecon\u00f4mico e indicar as modalidades de reserva de vagas que deseja concorrer.<br><\/p>\n\n\n\n<p>De acordo com o edital publicado pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), o processo seletivo ter\u00e1 somente uma etapa de inscri\u00e7\u00e3o para as vagas ofertadas. O resultado da chamada regular ser\u00e1 divulgado no dia 29 de janeiro de 2026, e a matr\u00edcula junto \u00e0s institui\u00e7\u00f5es come\u00e7a a partir de 2 de fevereiro de 2026.<br>Novidade<\/p>\n\n\n\n<p>A partir de 2026, o Sisu passar\u00e1 a considerar o resultado das tr\u00eas \u00faltimas edi\u00e7\u00f5es do Enem (2023, 2024 e 2025), considerando a nota da edi\u00e7\u00e3o que resulte na melhor m\u00e9dia ponderada, de acordo com a op\u00e7\u00e3o de curso. Em caso de empate na utiliza\u00e7\u00e3o das m\u00e9dias ponderadas, ser\u00e1 considerada a edi\u00e7\u00e3o do Enem em que o estudante obteve a maior nota em<br><\/p>\n\n\n\n<p>uma das disciplinas, conforme a ordem de prioridade.<\/p>\n\n\n\n<p>Somente poder\u00e3o se inscrever na edi\u00e7\u00e3o do Sisu de 2026 os candidatos que tenham participado de uma ou mais edi\u00e7\u00f5es com nota superior a zero na reda\u00e7\u00e3o e n\u00e3o tenha sido treineiro \u2500 estudante que n\u00e3o terminou o ensino m\u00e9dio e faz o exame para fins de autoavalia\u00e7\u00e3o.<\/p>\n\n\n\n<p>As vagas ser\u00e3o preenchidas pelas institui\u00e7\u00f5es segundo a ordem de classifica\u00e7\u00e3o dos candidatos e, no per\u00edodo de 29 de janeiro at\u00e9 2 de fevereiro de 2026, o candidato que n\u00e3o for selecionado na chamada regular poder\u00e1 manifestar interesse em participar da lista de espera.<br>Cotas<\/p>\n\n\n\n<p>De acordo com nota do MEC, os candidatos ser\u00e3o classificados na modalidade ampla concorr\u00eancia e, ap\u00f3s a etapa de classifica\u00e7\u00e3o, ser\u00e1 observada a propor\u00e7\u00e3o de estudantes de escolas p\u00fablicas, de baixa renda, com defici\u00eancia, pretos, pardos, ind\u00edgenas e quilombolas para a oferta de vagas reservadas.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Juca Varella \/ Ag\u00eancia Brasil As inscri\u00e7\u00f5es para a edi\u00e7\u00e3o do Sistema de Sele\u00e7\u00e3o Unificada (Sisu) 2026 come\u00e7ar\u00e3o no dia 19 de janeiro e poder\u00e3o ser feitas exclusivamente pela internet, at\u00e9 o dia 23 de janeiro. A edi\u00e7\u00e3o ser\u00e1 a maior em n\u00famero de institui\u00e7\u00f5es participantes, com 136 universidades, institutos federais e centros federais<\/p>\n","protected":false},"author":5,"featured_media":71683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-71682","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=71682"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71682\/revisions"}],"predecessor-version":[{"id":71684,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/71682\/revisions\/71684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/71683"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=71682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=71682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=71682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}