{"id":70725,"date":"2025-12-05T01:11:34","date_gmt":"2025-12-05T01:11:34","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=70725"},"modified":"2025-12-05T01:11:34","modified_gmt":"2025-12-05T01:11:34","slug":"governo-cria-grupo-para-debate-direitos-de-entregadores-por-aplicativo","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/12\/05\/governo-cria-grupo-para-debate-direitos-de-entregadores-por-aplicativo\/","title":{"rendered":"Governo cria grupo para debate direitos de entregadores por aplicativo"},"content":{"rendered":"\n<p><strong>Foto: Rovena Rosa\/Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>O governo federal vai instituir um grupo de trabalho (GT), coordenado pela Secretaria-Geral da Presid\u00eancia da Rep\u00fablica, para formular propostas de regula\u00e7\u00e3o trabalhista para entregadores por aplicativo.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1670964&amp;o=node\"><\/p>\n\n\n\n<p>O grupo ser\u00e1 composto tamb\u00e9m pelo Minist\u00e9rio do Trabalho e Emprego (MTE), o Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) e representantes de organiza\u00e7\u00f5es e entidades dos entregadores de todas as cinco regi\u00f5es do pa\u00eds, al\u00e9m de representantes das centrais sindicais.<\/p>\n\n\n\n<p>O an\u00fancio foi feito nesta quinta-feira (4), pelo ministro Guilherme Boulos, que se reuniu com representantes destes trabalhadores.<\/p>\n\n\n\n<p>Acess\u00f3rios para telem\u00f3veis<\/p>\n\n\n\n<p>Segundo o ministro, um dos principais objetivos da iniciativa \u00e9 melhorar a remunera\u00e7\u00e3o desses entregadores.<\/p>\n\n\n\n<p>&#8220;Hoje trabalham demais e ganham pouco&#8221;, sintetizou.<\/p>\n\n\n\n<p>O&nbsp;grupo tamb\u00e9m deve propor algum seguro previdenci\u00e1rio para a categoria.<\/p>\n\n\n\n<p>&#8220;O formato disso n\u00f3s queremos discutir exatamente no grupo de trabalho para esses trabalhadores que hoje, se sofrem um acidente, est\u00e3o a Deus dar\u00e1, ningu\u00e9m se responsabiliza&#8221;, disse Boulos.<\/p>\n\n\n\n<p>O terceiro ponto de pauta envolve&nbsp;transpar\u00eancia das plataformas no uso dos algoritmos, que s\u00e3o as programa\u00e7\u00f5es digitais das plataformas que definem quest\u00f5es como valor e distribui\u00e7\u00e3o das entregas a esses profissionais aut\u00f4nomos.<\/p>\n\n\n\n<p>&#8220;Tanto os motoristas de Uber, como os entregadores de ifood, e aqui tamb\u00e9m vale para todas outras plataformas, esses trabalhadores hoje s\u00e3o comandados pelo algoritmo, que inclusive utilizam os seus dados, mas n\u00e3o h\u00e1 nenhuma transpar\u00eancia nesse algoritmo. E \u00e9 uma demanda dos trabalhadores que haja essa transpar\u00eancia&#8221;, observou Boulos.<\/p>\n\n\n\n<p>Ser\u00e3o convidados a participar das reuni\u00f5es do grupo de trabalho representantes do Tribunal Superior do Trabalho (TST), do Minist\u00e9rio P\u00fablico do Trabalho (MPT) e do Minist\u00e9rio da Sa\u00fade. A Comiss\u00e3o Especial da C\u00e2mara dos Deputados sobre Regulamenta\u00e7\u00e3o dos Trabalhadores por App, por meio de seu presidente, o deputado Joaquim Passarinho (PL-PA), e o relator do colegiado, deputado federal Augusto Coutinho (Republicanos-PE), tamb\u00e9m ser\u00e3o chamados a contribuir com &nbsp;debate.<\/p>\n\n\n\n<p>Nesse primeiro momento, segundo Boulos, o grupo tratar\u00e1 apenas das demandas dos entregadores por aplicativo, separando das pautas dos motoristas aut\u00f4nomos.<\/p>\n\n\n\n<p>&#8220;N\u00f3s tomamos a defini\u00e7\u00e3o de separar os entregadores motoqueiros de motoristas porque existem pautas espec\u00edficas de cada um. Ent\u00e3o, embora o projeto de lei que est\u00e1&nbsp;em discuss\u00e3o na C\u00e2mara dos Deputados e que vai tramitar no Congresso Nacional, trate dos dois conjuntamente, aqui no governo do presidente de Lula n\u00f3s estamos fazendo essa separa\u00e7\u00e3o do debate&#8221;, explicou.<\/p>\n\n\n\n<p>Nicolas dos Santos, representante da Alian\u00e7a Nacional dos Empregadores por Aplicativos, espera que a cria\u00e7\u00e3o do grupo possa destravar um debate que se arrasta h\u00e1 cerca de quatro anos.<\/p>\n\n\n\n<p>&#8220;Foi promessa de campanha do atual presidente Lula e a gente espera que essa entrega seja realmente realizada. O debate no Congresso, ele n\u00e3o avan\u00e7a a contento, ele \u00e9 como se as ruas dissessem, mas isso n\u00e3o fosse ouvido&#8221;, afirmou o trabalhador.<\/p>\n\n\n\n<p>&#8220;A gente precisa ganhar bem, a gente precisa ter condi\u00e7\u00e3o de acessar aquilo que \u00e9 direito nosso, poder ter acesso a trabalho digno, moradia digna, condi\u00e7\u00e3o de dar educa\u00e7\u00e3o para os nossos filhos&#8221;, acrescentou.<\/p>\n\n\n\n<p>O GT ter\u00e1 dura\u00e7\u00e3o de 60 dias, com possibilidade de ser prorrogado, se necess\u00e1rio.<\/p>\n\n\n\n<p><strong>Mobiliza\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p>As manifesta\u00e7\u00f5es de entregadores por aplicativo t\u00eam sido recorrentes no pa\u00eds. Na semana passada,&nbsp;um grupo de entregadores protestou contra uma modalidade nova de trabalho do iFood.<\/p>\n\n\n\n<p>Em mar\u00e7o, uma mobiliza\u00e7\u00e3o nacional ocorreu em diversas capitais&nbsp;na luta por taxa m\u00ednima de R$ 10 por entrega.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 a primeira vez que o governo tenta avan\u00e7ar na pauta da categoria, sem sucesso. Ao longo de 2023, um outro grupo de trabalho, sobre coordena\u00e7\u00e3o do MTE, juntou representantes de plataformas e entregadores,&nbsp;mas n\u00e3o houve avan\u00e7os.<\/p>\n\n\n\n<p>Na C\u00e2mara, a comiss\u00e3o especial sobre o tema analisa o Projeto de Lei Complementar 152\/25, que define normas para o funcionamento de servi\u00e7os de transporte individual de passageiros e de entrega operados por plataformas digitais, como Uber, 99 e InDrive.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Rovena Rosa\/Ag\u00eancia Brasil O governo federal vai instituir um grupo de trabalho (GT), coordenado pela Secretaria-Geral da Presid\u00eancia da Rep\u00fablica, para formular propostas de regula\u00e7\u00e3o trabalhista para entregadores por aplicativo. O grupo ser\u00e1 composto tamb\u00e9m pelo Minist\u00e9rio do Trabalho e Emprego (MTE), o Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) e representantes de<\/p>\n","protected":false},"author":5,"featured_media":70726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-70725","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70725"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70725\/revisions"}],"predecessor-version":[{"id":70727,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70725\/revisions\/70727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/70726"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}