{"id":70364,"date":"2025-11-25T15:52:36","date_gmt":"2025-11-25T15:52:36","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=70364"},"modified":"2025-11-25T15:52:37","modified_gmt":"2025-11-25T15:52:37","slug":"embraer-vai-receber-r-1-bi-do-bndes-para-dinamizar-exportacoes","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/11\/25\/embraer-vai-receber-r-1-bi-do-bndes-para-dinamizar-exportacoes\/","title":{"rendered":"Embraer vai receber R$ 1 bi do BNDES para dinamizar exporta\u00e7\u00f5es"},"content":{"rendered":"\n<p>Foto: Antonio Milena\/Arquivo Abr<\/p>\n\n\n\n<p><strong>A terceira maior fabricante de avi\u00f5es do mundo, a <a href=\"https:\/\/agenciabrasil.ebc.com.br\/tags\/embraer\" target=\"_blank\" rel=\"noreferrer noopener\">Embraer<\/a>, vai receber um empr\u00e9stimo de R$ 1,09 bilh\u00e3o para produzir aeronaves comerciais que ser\u00e3o vendidas para o exterior<\/strong>. O financiamento foi aprovado pelo <a href=\"https:\/\/agenciabrasil.ebc.com.br\/tags\/bndes\">Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES)<\/a>, conforme comunicado divulgado pelo banco de fomento nesta ter\u00e7a-feira (25). Os recursos ser\u00e3o utilizados pela empresa para cumprir cronograma de entregas j\u00e1 acertado com importadores em v\u00e1rios pa\u00edses.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1669363&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1669363&amp;o=node\"><\/p>\n\n\n\n<p>A companhia, l\u00edder na fabrica\u00e7\u00e3o de jatos comerciais de at\u00e9 150 assentos, espera fechar 2025 com um total de 77 a 85 jatos comerciais entregues. No ano passado, o n\u00famero ficou em 73. Em 2023 foram 64. Somando avi\u00f5es comerciais e aeronaves de defesa e seguran\u00e7a foram 206 entregas em 2024 e 181 em 2023.<\/p>\n\n\n\n<p>Os recursos para o empr\u00e9stimo s\u00e3o da linha de financiamento Exim Pr\u00e9-embarque, voltado para exportadores, com taxas de juros formadas por custo financeiro, taxa do BNDES e taxa de risco de cr\u00e9dito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Recorde de pedidos<\/h2>\n\n\n\n<p>De acordo com o presidente da Embraer, Francisco Gomes Neto, a empresa vivencia um recorde no volume de pedidos e \u201critmo s\u00f3lido de vendas\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEstamos realizando investimentos significativos para atender \u00e0 crescente procura por nossos produtos e o financiamento do BNDES \u00e9 fundamental para apoiar iniciativas que visam aumentar a capacidade de produ\u00e7\u00e3o e acelerar as entregas nos pr\u00f3ximos anos\u201d, disse no comunicado do banco.<\/p>\n<\/blockquote>\n\n\n\n<p>O presidente do BNDES, Aloizio Mercadante, destaca o fato de o Brasil fazer parte de um \u201cseleto grupo\u201d de pa\u00edses com capacidade de projetar, fabricar e exportar aeronaves comerciais, executivas, de defesa e agr\u00edcolas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/cNKlO8LQH46sKwP8XVodQ1ntuBw=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/2025\/08\/28\/_d6a1761.jpg?itok=mBgtyddh\" alt=\"Rio de Janeiro (RJ), 28\/08\/2025 \u2013 O presidente do BNDES, Alu\u00edzio Mercadante, recebe o prefeito do Rio, Eduardo Paes, presidente da Frente Nacional de Prefeitas e Prefeitos (FPN), al\u00e9m de prefeitos representantes outros munic\u00edpios para detalhar as medidas de apoio do Plano Brasil Soberano. Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil\" title=\"Fernando Fraz\u00e3o\/Ag\u00eancia Brasil\"\/><\/figure>\n\n\n\n<p>Rio de Janeiro (RJ), 28\/08\/2025 \u2013 O presidente do BNDES, Alu\u00edzio Mercadante. Foto-arquivo: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil &#8211; <strong>Fernando Fraz\u00e3o\/Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201c\u00c9 um setor estrat\u00e9gico, devido \u00e0 alta tecnologia envolvida, ao emprego de m\u00e3o de obra com alta capacita\u00e7\u00e3o e \u00e0 capacidade de gerar inova\u00e7\u00f5es com impactos positivos na economia do Brasil\u201d, afirmou Mercadante.<\/p>\n<\/blockquote>\n\n\n\n<p>O banco, vinculado ao Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, financiou cerca de US$ 26,3 bilh\u00f5es em exporta\u00e7\u00f5es de aeronaves comerciais da Embraer, apoiando a produ\u00e7\u00e3o de 1.350 jatos, desde 1997.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Embraer<\/h2>\n\n\n\n<p>A Embraer tem 23,5 mil funcion\u00e1rios em todo o mundo, sendo 18 mil no Brasil, principalmente na sede em S\u00e3o Jos\u00e9 dos Campos, em S\u00e3o Paulo.<\/p>\n\n\n\n<p>H\u00e1 contingente tamb\u00e9m nas cidades paulistas de Sorocaba, Botucatu e Gavi\u00e3o Peixoto, al\u00e9m de engenheiros em Florian\u00f3polis e Belo Horizonte.<\/p>\n\n\n\n<p>A empresa mant\u00e9m unidades industriais nos Estados Unidos e em Portugal. A maior parte das vendas da Embraer \u00e9 destinada ao mercado externo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Antonio Milena\/Arquivo Abr A terceira maior fabricante de avi\u00f5es do mundo, a Embraer, vai receber um empr\u00e9stimo de R$ 1,09 bilh\u00e3o para produzir aeronaves comerciais que ser\u00e3o vendidas para o exterior. O financiamento foi aprovado pelo Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES), conforme comunicado divulgado pelo banco de fomento nesta ter\u00e7a-feira (25).<\/p>\n","protected":false},"author":5,"featured_media":70365,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-70364","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70364"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70364\/revisions"}],"predecessor-version":[{"id":70366,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70364\/revisions\/70366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/70365"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}