{"id":70187,"date":"2025-11-21T01:57:22","date_gmt":"2025-11-21T01:57:22","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=70187"},"modified":"2025-11-21T01:57:22","modified_gmt":"2025-11-21T01:57:22","slug":"lider-do-pt-questiona-no-stf-e-na-camara-saida-de-ramagem-do-pais","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/11\/21\/lider-do-pt-questiona-no-stf-e-na-camara-saida-de-ramagem-do-pais\/","title":{"rendered":"L\u00edder do PT questiona no STF e na C\u00e2mara sa\u00edda de Ramagem do pa\u00eds"},"content":{"rendered":"\n<p>Foto: Gustavo Moreno\/STF \/ Ag\u00eancia Brasil<\/p>\n\n\n\n<p><strong>O l\u00edder da bancada do PT na C\u00e2mara, Lindbergh Farias (RJ), protocolou nesta quinta-feira (20) medidas no Supremo Tribunal Federal (STF) e na Mesa Diretora da C\u00e2mara questionando a sa\u00edda do deputado Alexandre Ramagem (PL-RJ) do pa\u00eds, apesar de medidas cautelares que o proibiam de&nbsp;deixar&nbsp;o Brasil.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1668873&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1668873&amp;o=node\"><\/p>\n\n\n\n<p>Segundo Lindbergh, o que est\u00e1 em jogo \u00e9 a autoridade das institui\u00e7\u00f5es. \u201cUm parlamentar condenado por crimes graves contra a democracia n\u00e3o pode fugir para Miami como se nada tivesse acontecido. A lei vale para todos e ir\u00e1 imperar contra o deputado fugitivo que seguiu o exemplo de Carla Zambelli, Eduardo Bolsonaro, entre outros\u201d,&nbsp;ressaltou o l\u00edder do PT.<\/p>\n\n\n\n<p>Esta semana, deputados do PSOL-RJ (Pastor Henrique Vieira, Glauber Braga, Chico Alencar, Tarc\u00edsio Motta e Tal\u00edria Petrone) pediram ao STF a <a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2025-11\/psol-pede-prisao-de-ramagem-apos-deputado-ser-visto-em-miami\" target=\"_blank\" rel=\"noreferrer noopener\">decreta\u00e7\u00e3o da pris\u00e3o de Ramagem<\/a>, argumentando que \u201ctudo indica&nbsp;que ele fugiu para os Estados Unidos\u201d.<\/p>\n\n\n\n<p>A C\u00e2mara, por sua vez, afirmou que <a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2025-11\/camara-diz-que-nao-foi-informada-sobre-saida-de-ramagem-do-pais\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o foi informada oficialmente<\/a> sobre a sa\u00edda de Ramagem nem autorizou viagem oficial ao exterior.<\/p>\n\n\n\n<p>Ex-diretor da Ag\u00eancia Brasileira de Intelig\u00eancia (Abin) durante o governo Jair Bolsonaro, Ramagem foi <a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2025-09\/confira-penas-de-bolsonaro-e-mais-sete-condenados-pelo-supremo\" target=\"_blank\" rel=\"noreferrer noopener\">condenado na a\u00e7\u00e3o penal da trama golpista a 16 anos de pris\u00e3o<\/a> e recorre em liberdade.<\/p>\n\n\n\n<p>Durante a investiga\u00e7\u00e3o, <strong>Ramagem foi proibido pelo ministro Alexandre de Moraes de sair do pa\u00eds e teve que entregar todos os passaportes nacionais e estrangeiros<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Gustavo Moreno\/STF \/ Ag\u00eancia Brasil O l\u00edder da bancada do PT na C\u00e2mara, Lindbergh Farias (RJ), protocolou nesta quinta-feira (20) medidas no Supremo Tribunal Federal (STF) e na Mesa Diretora da C\u00e2mara questionando a sa\u00edda do deputado Alexandre Ramagem (PL-RJ) do pa\u00eds, apesar de medidas cautelares que o proibiam de&nbsp;deixar&nbsp;o Brasil. Segundo Lindbergh, o<\/p>\n","protected":false},"author":5,"featured_media":70188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[71],"tags":[],"class_list":{"0":"post-70187","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70187"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70187\/revisions"}],"predecessor-version":[{"id":70189,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70187\/revisions\/70189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/70188"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}