{"id":70149,"date":"2025-11-20T02:42:26","date_gmt":"2025-11-20T02:42:26","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=70149"},"modified":"2025-11-20T02:42:26","modified_gmt":"2025-11-20T02:42:26","slug":"fim-do-master-trabalhadores-e-12-milhoes-de-clientes-serao-afetados","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/11\/20\/fim-do-master-trabalhadores-e-12-milhoes-de-clientes-serao-afetados\/","title":{"rendered":"Fim do Master: trabalhadores e 12 milh\u00f5es de clientes ser\u00e3o afetados"},"content":{"rendered":"\n<p><strong>Foto: Jos\u00e9 Cruz \/ Ag\u00eancia Brasil<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>O Sindicato dos Banc\u00e1rios de S\u00e3o Paulo, Osasco e Regi\u00e3o disse nesta quarta-feira (19) que a determina\u00e7\u00e3o do Banco Central de&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-11\/banco-central-oficializa-liquidacao-da-master-corretora\" target=\"_blank\" rel=\"noreferrer noopener\">liquida\u00e7\u00e3o do&nbsp;Banco Master<\/a>&nbsp;deve impactar&nbsp;515 trabalhadores e 12 milh\u00f5es de clientes.&nbsp;<\/strong>O \u00f3rg\u00e3o tamb\u00e9m analisa os poss\u00edveis efeitos indiretos sobre o Will Bank, que faz parte do conglomerado Master.<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1668630&amp;o=node\">Em nota oficial, o sindicato avisa que \u201csegue atento, cobrando transpar\u00eancia e buscando todas as informa\u00e7\u00f5es necess\u00e1rias para proteger os direitos dos trabalhadores e garantir que qualquer a\u00e7\u00e3o siga rigorosamente a Conven\u00e7\u00e3o Coletiva de Trabalho (CCT) da categoria e a legisla\u00e7\u00e3o vigente\u201c.<\/p>\n\n\n\n<p>A associa\u00e7\u00e3o tamb\u00e9m diz esperar que &#8220;as solu\u00e7\u00f5es passem pela prote\u00e7\u00e3o ao emprego dos trabalhadores, que n\u00e3o podem ser penalizados pelos atos praticados pelos gestores do banco&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fim do Master<\/h2>\n\n\n\n<p>Na \u00faltima ter\u00e7a-feira (18), o Banco Central oficializou a liquida\u00e7\u00e3o extrajudicial do Banco Master. A decis\u00e3o est\u00e1 relacionada \u00e0 Opera\u00e7\u00e3o Compliance Zero, que apura e combater a emiss\u00e3o de t\u00edtulos de cr\u00e9ditos falsos por institui\u00e7\u00f5es que fazem parte do Sistema Financeiro Nacional.<\/p>\n\n\n\n<p>A medida resultou na pris\u00e3o do dono da entidade, Daniel Vorcaro, no Aeroporto de Guarulhos na noite da segunda-feira (17). A empresa era suspeita de criar falsas opera\u00e7\u00f5es de cr\u00e9ditos, simulando empr\u00e9stimos e outros valores a receber.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o tamb\u00e9m causou o afastamento tempor\u00e1rio do presidente do banco BRB, Paulo Henrique Costa, e do diretor de Finan\u00e7as e Controladoria da institui\u00e7\u00e3o, Dario Oswaldo Garcia Junior, por decreto da Justi\u00e7a.<\/p>\n\n\n\n<p>O banco estatal do Distrito Federal havia anunciado em mar\u00e7o deste ano a inten\u00e7\u00e3o de comprar o Master por R$ 2 bilh\u00f5es, por\u00e9m, a opera\u00e7\u00e3o foi n\u00e3o foi autorizada pelo Banco Central.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Jos\u00e9 Cruz \/ Ag\u00eancia Brasil O Sindicato dos Banc\u00e1rios de S\u00e3o Paulo, Osasco e Regi\u00e3o disse nesta quarta-feira (19) que a determina\u00e7\u00e3o do Banco Central de&nbsp;liquida\u00e7\u00e3o do&nbsp;Banco Master&nbsp;deve impactar&nbsp;515 trabalhadores e 12 milh\u00f5es de clientes.&nbsp;O \u00f3rg\u00e3o tamb\u00e9m analisa os poss\u00edveis efeitos indiretos sobre o Will Bank, que faz parte do conglomerado Master. Em nota<\/p>\n","protected":false},"author":5,"featured_media":70150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-70149","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70149"}],"version-history":[{"count":2,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70149\/revisions"}],"predecessor-version":[{"id":70152,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70149\/revisions\/70152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/70150"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}