{"id":70080,"date":"2025-11-18T01:54:02","date_gmt":"2025-11-18T01:54:02","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=70080"},"modified":"2025-11-18T01:54:03","modified_gmt":"2025-11-18T01:54:03","slug":"enem-2025-pedido-de-reaplicacao-de-provas-comeca-nesta-segunda","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/11\/18\/enem-2025-pedido-de-reaplicacao-de-provas-comeca-nesta-segunda\/","title":{"rendered":"Enem 2025: pedido de reaplica\u00e7\u00e3o de provas come\u00e7a nesta segunda"},"content":{"rendered":"\n<p><strong>Foto: Romildo de Jesus\/Tribuna da Bahia<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Os participantes que perderam a aplica\u00e7\u00e3o de um ou dois dias de provas do Enem afetados por problemas log\u00edsticos, desastres naturais ou doen\u00e7as infectocontagiosas poder\u00e3o solicitar a reaplica\u00e7\u00e3o do exame a partir desta segunda-feira (17) at\u00e9 as 12h da pr\u00f3xima sexta-feira (21), no hor\u00e1rio de Bras\u00edlia.<\/p>\n\n\n\n<p>Descobrir mais<\/p>\n\n\n\n<p>Publicidade legal<\/p>\n\n\n\n<p>Eventos Salvador<\/p>\n\n\n\n<p>Esporte not\u00edcias<\/p>\n\n\n\n<p>Aulas de dan\u00e7a regional<\/p>\n\n\n\n<p>Livros sobre pol\u00edtica<\/p>\n\n\n\n<p>Jornal online<\/p>\n\n\n\n<p>Not\u00edcias Salvador<\/p>\n\n\n\n<p>Educa\u00e7\u00e3o not\u00edcias<\/p>\n\n\n\n<p>Equipamentos eletr\u00f3nicos<\/p>\n\n\n\n<p>Roupas desportivas<\/p>\n\n\n\n<p>&nbsp; &nbsp; \u201cTodos os que se sentirem prejudicados, por exemplo, pela falta de energia e fatores externos \u00e0s escolas, ter\u00e3o direito \u00e0 reaplica\u00e7\u00e3o nos dias 16 e 17 de dezembro.&#8221;<\/p>\n\n\n\n<p>O Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep) avisa que haver\u00e1 apenas uma reaplica\u00e7\u00e3o do Enem.<\/p>\n\n\n\n<p><strong>Como solicitar<\/strong><\/p>\n\n\n\n<p>A solicita\u00e7\u00e3o dever\u00e1 ser feita por meio da P\u00e1gina do Participante, no site do Inep, com login de acesso pela plataforma Gov.br.<\/p>\n\n\n\n<p>Para a an\u00e1lise, o participante dever\u00e1 inserir um documento leg\u00edvel, em l\u00edngua portuguesa, que comprove a condi\u00e7\u00e3o que motiva a solicita\u00e7\u00e3o de atendimento, com a data que contemple o dia perdido de aplica\u00e7\u00e3o do Enem 2025.&nbsp;<\/p>\n\n\n\n<p><strong>Situa\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p>Os participantes de cidades afetadas por desastres naturais ter\u00e3o a reaplica\u00e7\u00e3o do exame garantida.<\/p>\n\n\n\n<p>O ministro da Educa\u00e7\u00e3o, Camilo Santana, lembrou os candidatos que tiveram o Enem suspenso em Rio Bonito do Igua\u00e7u, no centro-sul do Paran\u00e1, ap\u00f3s a passagem de um tornado no dia 7 de novembro. O munic\u00edpio ficou 90% destru\u00eddo, de acordo com a Defesa Civil do estado.<\/p>\n\n\n\n<p>O edital de abertura do Enem prev\u00ea que o participante afetado por problemas log\u00edsticos durante a aplica\u00e7\u00e3o das provas ou acometido por doen\u00e7a infectocontagiosa no primeiro ou no segundo dia das provas poder\u00e1 solicitar a reaplica\u00e7\u00e3o.&nbsp;<br>Doen\u00e7as infecciosas<\/p>\n\n\n\n<p>De acordo com o edital do Enem 2025, o participante infectado por uma das doen\u00e7as a seguir dever\u00e1 solicitar reaplica\u00e7\u00e3o: tuberculose, coqueluche, difteria, doen\u00e7a invasiva por Haemophilus influenzae, doen\u00e7a meningoc\u00f3cica e outras meningites, var\u00edola, var\u00edola dos macacos (monkeypox), influenza humana A e B, poliomielite por poliov\u00edrus selvagem, sarampo, rub\u00e9ola, varicela (catapora) ou covid-19.<\/p>\n\n\n\n<p>Descobrir mais<\/p>\n\n\n\n<p>Suplementos nutricionais<\/p>\n\n\n\n<p>Viagens para a Bahia<\/p>\n\n\n\n<p>Eventos Salvador<\/p>\n\n\n\n<p>Jornalismo investigativo<\/p>\n\n\n\n<p>Guias tur\u00edsticos de Salvador<\/p>\n\n\n\n<p>Produtos de sa\u00fade e bem-estar<\/p>\n\n\n\n<p>Not\u00edcias Bahia<\/p>\n\n\n\n<p>Cosm\u00e9ticos e maquilhagem<\/p>\n\n\n\n<p>Livros sobre pol\u00edtica<\/p>\n\n\n\n<p>Economia local<\/p>\n\n\n\n<p><strong>Problemas log\u00edsticos<\/strong><\/p>\n\n\n\n<p>Para reaplica\u00e7\u00e3o, s\u00e3o considerados problemas log\u00edsticos que prejudicaram o solicitante como: desastres naturais que comprometam a infraestrutura do local; falta de energia el\u00e9trica que comprometa a visibilidade da prova pela aus\u00eancia de luz natural ou outro erro de execu\u00e7\u00e3o de procedimento de aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>An\u00e1lise<\/strong><\/p>\n\n\n\n<p>Cada caso ser\u00e1 analisado individualmente pela equipe do Inep. Somente a aprova\u00e7\u00e3o do documento comprobat\u00f3rio garante a participa\u00e7\u00e3o na reaplica\u00e7\u00e3o do exame.<\/p>\n\n\n\n<p>Para os casos em que o pedido for aceito (deferido), as provas ser\u00e3o reaplicadas nos dias 16 e 17 de dezembro.<\/p>\n\n\n\n<p>O inscrito far\u00e1 a prova somente do dia em que sua participa\u00e7\u00e3o foi inviabilizada no Enem.<\/p>\n\n\n\n<p>Fonte: ag\u00eancia brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Romildo de Jesus\/Tribuna da Bahia Os participantes que perderam a aplica\u00e7\u00e3o de um ou dois dias de provas do Enem afetados por problemas log\u00edsticos, desastres naturais ou doen\u00e7as infectocontagiosas poder\u00e3o solicitar a reaplica\u00e7\u00e3o do exame a partir desta segunda-feira (17) at\u00e9 as 12h da pr\u00f3xima sexta-feira (21), no hor\u00e1rio de Bras\u00edlia. Descobrir mais Publicidade<\/p>\n","protected":false},"author":5,"featured_media":70081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-70080","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=70080"}],"version-history":[{"count":2,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70080\/revisions"}],"predecessor-version":[{"id":70084,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/70080\/revisions\/70084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/70081"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=70080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=70080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=70080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}