{"id":65575,"date":"2025-06-04T15:08:55","date_gmt":"2025-06-04T15:08:55","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=65575"},"modified":"2025-06-04T15:08:56","modified_gmt":"2025-06-04T15:08:56","slug":"desaprovacao-ao-governo-lula-chega-a-57-maior-indice-do-mandato-diz-pesquisa-genial-quaest","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2025\/06\/04\/desaprovacao-ao-governo-lula-chega-a-57-maior-indice-do-mandato-diz-pesquisa-genial-quaest\/","title":{"rendered":"Desaprova\u00e7\u00e3o ao governo Lula chega a 57%, maior \u00edndice do mandato, diz pesquisa Genial\/Quaest"},"content":{"rendered":"\n<p>A desaprova\u00e7\u00e3o ao governo do presidente Luiz In\u00e1cio Lula da Silva (PT) chegou em maio a 57%, o maior \u00edndice desde o in\u00edcio do terceiro mandato, segundo pesquisa Genial\/Quaest divulgada nesta quarta-feira (4). Na rodada anterior, em mar\u00e7o, o percentual era de 56%. J\u00e1 a aprova\u00e7\u00e3o registrada agora \u00e9 de 40%, ante 41% no outro levantamento, que j\u00e1 tinha sido o pior na s\u00e9rie hist\u00f3rica.<\/p>\n\n\n\n<p>A avalia\u00e7\u00e3o negativa do governo Lula tamb\u00e9m oscilou para cima e atingiu o pico na s\u00e9rie hist\u00f3rica da pesquisa, chegando a 43%, ante 41% em mar\u00e7o. A positiva foi de 27% para 26%. A regular era de 29% e agora \u00e9 de 28%. Para 61%, o Brasil est\u00e1 na dire\u00e7\u00e3o errada, acima do patamar de 56% em mar\u00e7o e do de 50% em janeiro. S\u00e3o 32% os que acham que o pa\u00eds e est\u00e1 na dire\u00e7\u00e3o certa, ante 36% e 39% nas duas rodadas anteriores, respectivamente.<\/p>\n\n\n\n<p>Pela primeira vez, a desaprova\u00e7\u00e3o do governo Lula superou a aprova\u00e7\u00e3o entre os cat\u00f3licos, na propor\u00e7\u00e3o de 53% a 49%. Em mar\u00e7o, os resultados estavam empatados, em 49%. O segmento, at\u00e9 ent\u00e3o, demonstrava maior apoio do que o de evang\u00e9licos, que sempre foi mais avesso ao presidente. Na nova rodada, a desaprova\u00e7\u00e3o no segundo grupo ficou em 66% (ante 67% na pesquisa anterior) e a aprova\u00e7\u00e3o foi de 30% (eram 29%).<\/p>\n\n\n\n<p>A pesquisa traz ainda resultados ruins para o governo na base tradicional de apoio a Lula. O governo dele \u00e9 desaprovado por 54% das mulheres, por 47% dos que t\u00eam at\u00e9 o ensino fundamental e por 49% dos que ganham at\u00e9 dois sal\u00e1rios m\u00ednimos. Nos tr\u00eas estratos, a tend\u00eancia foi de alta, com varia\u00e7\u00f5es dentro da margem de erro.<\/p>\n\n\n\n<p>No recorte por regi\u00f5es, Lula s\u00f3 tem aprova\u00e7\u00e3o maior que reprova\u00e7\u00e3o no Nordeste, com 54% favor\u00e1veis a seu governo e 44% contr\u00e1rios. No Sudeste, a regi\u00e3o mais populosa, a reprova\u00e7\u00e3o bate 64%, um recorde. No Sul, 62%. No Centro-Oeste, 55%.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2ec808beaf468455a9d0f0cb46d76365\">Melhora na economia<\/p>\n\n\n\n<p>Embora os n\u00fameros confirmem a crise de popularidade de Lula, a pesquisa mostra uma melhora na percep\u00e7\u00e3o econ\u00f4mica. A opini\u00e3o de que a economia do Brasil piorou totaliza 48%, 8 pontos percentuais abaixo do registrado em mar\u00e7o, que era de 56%. Para 18%, a economia melhorou (eram 16%). E 30% consideram que ela ficou do mesmo jeito (eram 26%).<\/p>\n\n\n\n<p>Tamb\u00e9m h\u00e1 algum al\u00edvio nos percentuais de aprova\u00e7\u00e3o entre pessoas que conhecem novos projetos oficiais do governo. No caso da proposta de isen\u00e7\u00e3o de Imposto de Renda para quem ganha at\u00e9 R$ 5 mil mensais, 56% dos entrevistados dizem que ouviram falar da iniciativa e 45% aprovam a medida. Em rela\u00e7\u00e3o \u00e0 proposta do novo Vale-G\u00e1s, 59% tomaram conhecimen Em rela\u00e7\u00e3o \u00e0 proposta do novo Vale-G\u00e1s, 59% tomaram conhecimento e 49% aprovam a a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Em relat\u00f3rio distribu\u00eddo com a pesquisa, o cientista pol\u00edtico e CEO da Quaest, Felipe Nunes, avaliou o quadro como um paradoxo e atribuiu a contradi\u00e7\u00e3o \u00e0 &#8220;ampla repercuss\u00e3o de not\u00edcias negativas&#8221;. Segundo ele, casos como o esc\u00e2ndalo das fraudes nos benef\u00edcios do Instituto Nacional do Seguro Social (INSS) reduzem o efeito positivo de outras \u00e1reas.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#abb7c240\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<ul class=\"wp-block-list\">\n<li>De acordo com a pesquisa, 50% das pessoas t\u00eam visto not\u00edcias mais negativas sobre o governo do que positivas. Uma parcela de 51% responde que n\u00e3o ouviu nenhuma not\u00edcia positiva sobre a gest\u00e3o.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p>Para 56%, o atual governo Lula est\u00e1 pior que os dois primeiros mandatos dele na Presid\u00eancia. Na compara\u00e7\u00e3o com o governo do ex-presidente Jair Bolsonaro (PL), 44% acham que a gest\u00e3o Lula \u00e9 pior que a do antecessor. E 45% dos entrevistados consideram que o governo Lula 3 est\u00e1 pior do que esperavam.<\/p>\n\n\n\n<p>Sobre as mudan\u00e7as no IOF, o percentual dos que ficaram sabendo dos reajustes \u00e9 menor do que o daqueles que desconhecem a informa\u00e7\u00e3o (39% e 58%, respectivamente). Para 41%, o governo acertou ao voltar atr\u00e1s na decis\u00e3o de aumentar o imposto para aplica\u00e7\u00f5es de investimento em fundos, enquanto 36% acham que errou.<\/p>\n\n\n\n<p>J\u00e1 em rela\u00e7\u00e3o \u00e0 manuten\u00e7\u00e3o do aumento do IOF para compra de d\u00f3lares para pessoas f\u00edsicas e remessa de dinheiro para contas no exterior, 50% avaliam que o governo errou com a decis\u00e3o, e 28% dizem que acertou.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f7a9cbd7941ff92b15f696f8ad24b4ae\">Esc\u00e2ndalo do INSS e aumento do IOF<\/p>\n\n\n\n<p>Uma parcela de 82% confirmou ter ficado sabendo do esc\u00e2ndalo no INSS, sendo que 31% pensam que o principal respons\u00e1vel pelos desvios \u00e9 o governo Lula e 14% afirmam que foi o pr\u00f3prio INSS. Para 8%, o maior culpado foi o governo Bolsonaro, mesmo percentual dos que acreditam que foram as entidades que fraudaram a a assinatura dos aposentados. A parcela dos que n\u00e3o sabem ou n\u00e3o responderam \u00e9 de 26%.<\/p>\n\n\n\n<p>A abertura de uma comiss\u00e3o parlamentar de inqu\u00e9rito (CPI) para investigar o caso do INSS \u00e9 defendida por 50%, enquanto 43% concordam com a ideia de que a apura\u00e7\u00e3o da Pol\u00edcia Federal \u00e9 suficiente, e que a oposi\u00e7\u00e3o s\u00f3 quer desgastar o governo.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-489f976f02257f6b055b2cb59a73c66c\">Viol\u00eancia e corrup\u00e7\u00e3o entre maiores preocupa\u00e7\u00f5es<br><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f89b49cf3a9bc8d30c3fd9d57ac237d4\">A viol\u00eancia se manteve no topo das principais preocupa\u00e7\u00f5es do brasileiro em rela\u00e7\u00e3o ao pa\u00eds atual, com 30% das men\u00e7\u00f5es. A lista prossegue com quest\u00f5es sociais (22%), em segundo lugar, e economia (19%), em terceiro.<\/p>\n\n\n\n<p>A quarta posi\u00e7\u00e3o teve uma mudan\u00e7a na compara\u00e7\u00e3o com a pesquisa de mar\u00e7o. Antes, Antes, aparecia sa\u00fade, com 12%. Agora, \u00e9 a corrup\u00e7\u00e3o, citada por 13% (antes, era citada por 10%). Na nova rodada, sa\u00fade tem 10% das men\u00e7\u00f5es, ficando em quinto lugar \u2014 as varia\u00e7\u00f5es entre os levantamentos ficaram dentro da margem de erro. Na sexta coloca\u00e7\u00e3o, est\u00e1 educa\u00e7\u00e3o, com 6%.<\/p>\n\n\n\n<p>Fonte: Valor Econ\u00f4mico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A desaprova\u00e7\u00e3o ao governo do presidente Luiz In\u00e1cio Lula da Silva (PT) chegou em maio a 57%, o maior \u00edndice desde o in\u00edcio do terceiro mandato, segundo pesquisa Genial\/Quaest divulgada nesta quarta-feira (4). Na rodada anterior, em mar\u00e7o, o percentual era de 56%. J\u00e1 a aprova\u00e7\u00e3o registrada agora \u00e9 de 40%, ante 41% no outro<\/p>\n","protected":false},"author":3,"featured_media":65576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[71],"tags":[],"class_list":{"0":"post-65575","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/65575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=65575"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/65575\/revisions"}],"predecessor-version":[{"id":65577,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/65575\/revisions\/65577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/65576"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=65575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=65575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=65575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}