{"id":60685,"date":"2024-11-15T18:42:12","date_gmt":"2024-11-15T18:42:12","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=60685"},"modified":"2024-11-15T18:42:13","modified_gmt":"2024-11-15T18:42:13","slug":"tudo-sobre-a-fuvest-2025-datas-questoes-local-o-que-levar-e-mais","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/11\/15\/tudo-sobre-a-fuvest-2025-datas-questoes-local-o-que-levar-e-mais\/","title":{"rendered":"Tudo sobre a Fuvest 2025: datas, quest\u00f5es, local, o que levar e mais"},"content":{"rendered":"\n<p>Na primeira etapa do processo, os estudantes ter\u00e3o que responder 90 quest\u00f5es de m\u00faltipla escolha<\/p>\n\n\n\n<p>O vestibular da Fuvest (Funda\u00e7\u00e3o Universit\u00e1ria para o Vestibular), para ingresso nos cursos de gradua\u00e7\u00e3o da USP (Universidade de S\u00e3o Paulo), come\u00e7a neste domingo (17).<\/p>\n\n\n\n<p>De agora em diante, os alunos t\u00eam pouco tempo para revisar os t\u00f3picos mais importantes das provas e, sobretudo, se preparar psicologicamente.<\/p>\n\n\n\n<p>A seguir, a CNN reuniu as principais informa\u00e7\u00f5es sobre a Fuvest:<\/p>\n\n\n\n<p>Cronograma da 1\u00aa fase:<br>In\u00edcio da entrada no local de prova: 12h<br>Fechamento dos port\u00f5es e in\u00edcio da prova: 13h<br>Permitido sair do local de prova: 16h<br>Divulga\u00e7\u00e3o do gabarito: 19h<br>Conte\u00fado da prova da 1\u00aa fase<br>Nesta primeira etapa do processo, os estudantes ter\u00e3o que responder 90 quest\u00f5es de m\u00faltipla escolha. Cada quest\u00e3o vale um ponto. A prova tem 5h de dura\u00e7\u00e3o, com in\u00edcio \u00e0s 13h e encerramento \u00e0s 18h.<\/p>\n\n\n\n<p>O conte\u00fado da prova \u00e9 de conhecimentos gerais e aborda as seguintes disciplinas do n\u00facleo obrigat\u00f3rio do ensino m\u00e9dio:<\/p>\n\n\n\n<p>Biologia;<br>F\u00edsica;<br>Geografia;<br>Hist\u00f3ria;<br>Ingl\u00eas;<br>Matem\u00e1tica;<br>Portugu\u00eas;<br>Qu\u00edmica.<br>Os locais de prova est\u00e3o dispon\u00edveis no site da Fuvest desde o in\u00edcio de novembro. \u00c9 essencial verificar com anteced\u00eancia para planejar o deslocamento e evitar imprevistos.<\/p>\n\n\n\n<p>Quando ser\u00e1 a 2\u00aa fase?<br>A lista de convoca\u00e7\u00e3o dos alunos que passaram para a segunda fase sair\u00e1 no dia 2 de dezembro. As provas ser\u00e3o nos dias 15 e 16 de dezembro, incluindo portugu\u00eas e reda\u00e7\u00e3o, al\u00e9m de disciplinas espec\u00edficas.<\/p>\n\n\n\n<p>Nos dois dias, as provas t\u00eam dura\u00e7\u00e3o de 4h, sendo realizadas das 13h \u00e0s 17h.<\/p>\n\n\n\n<p>Cronograma da 2\u00aa fase:<br>In\u00edcio da entrada no local de prova: 12h<br>Fechamento dos port\u00f5es e in\u00edcio da prova: 13h<br>Permitido sair do local de prova: 15h<br>Divulga\u00e7\u00e3o dos enunciados: 18h<br>Conte\u00fado das provas da 2\u00aa fase<br>Nesta etapa, s\u00e3o avaliadas as compet\u00eancias para a articula\u00e7\u00e3o de informa\u00e7\u00f5es e conhecimentos em todas as disciplinas e, com mais profundidade, nas que est\u00e3o diretamente ligadas ao curso pretendido pelo estudante. As quest\u00f5es s\u00e3o discursivas.<\/p>\n\n\n\n<p>Primeiro dia: 10 quest\u00f5es discursivas de portugu\u00eas, sobre interpreta\u00e7\u00e3o de textos, gram\u00e1tica e literatura, considerando a lista obrigat\u00f3ria de livros, e uma reda\u00e7\u00e3o;<br>Segundo dia: 12 quest\u00f5es discursivas de duas a quatro disciplinas espec\u00edficas \u00e0 carreira inscrita.<br>O que levar para realizar as provas?<br>De acordo com a Fuvest, apenas o b\u00e1sico \u00e9 necess\u00e1rio para realizar as provas do vestibular: seu documento de identifica\u00e7\u00e3o e uma caneta para escrever.<\/p>\n\n\n\n<p>Itens necess\u00e1rios para os dias de prova:<\/p>\n\n\n\n<p>Documento de identifica\u00e7\u00e3o, digital ou f\u00edsico;<br>Caneta esferogr\u00e1fica, azul ou preta, de corpo transparente.<br>Itens opcionais que podem ser utilizados:<\/p>\n\n\n\n<p>Garrafa de \u00e1gua;<br>Alimentos leves;<br>L\u00e1pis ou lapiseira;<br>Borracha;<br>Apontador;<br>R\u00e9gua transparente;<br>Itens m\u00e9dicos autorizados com anteced\u00eancia.<br>O que n\u00e3o poder\u00e1 ser utilizado nos locais de prova?<br>Rel\u00f3gio individual de qualquer tipo;<br>Equipamento eletr\u00f4nico, como calculadora, telefone celular, computador, tablet, reprodutor de \u00e1udio, m\u00e1quina fotogr\u00e1fica, equipamento eletr\u00f4nico do tipo vest\u00edvel (como smartwatch, \u00f3culos eletr\u00f4nicos, ponto eletr\u00f4nico) etc;<br>Material impresso ou para anota\u00e7\u00f5es;<br>Corretivo de qualquer material ou esp\u00e9cie;<br>Caneta hidrogr\u00e1fica ou outras, diferentes de caneta esferogr\u00e1fica;<br>Caneta marca-texto, compasso ou l\u00e1pis com tabuada;<br>Gorro, bon\u00e9, chap\u00e9u ou similares, \u00f3culos de sol;<br>Protetor auricular, fone de ouvido ou similares;<br>Quaisquer outros materiais estranhos \u00e0 realiza\u00e7\u00e3o da prova.<br>USP oferece 8.147 vagas em 2025<br>Em 2025, s\u00e3o oferecidas 8.147 vagas por meio da Fuvest. Outras 3 mil vagas s\u00e3o distribu\u00eddas a partir das avalia\u00e7\u00f5es do Enem-USP e Prov\u00e3o Paulista.<\/p>\n\n\n\n<p>Os resultados oficiais do vestibular ser\u00e3o divulgados na p\u00e1gina da Fuvest no dia 24 de janeiro de 2025. Ser\u00e3o disponibilizadas duas listas de chamada para matr\u00edcula, al\u00e9m das listas de espera.<\/p>\n\n\n\n<p>Calend\u00e1rio da Fuvest 2025:<br>1\u00aa fase Fuvest 2025: 17 novembro de 2024;<br>Divulga\u00e7\u00e3o dos convocados para a 2\u00aa fase: 2 de dezembro de 2024;<br>2\u00aa fase Fuvest 2025: 15 e 16 dezembro de 2024;<br>Provas de compet\u00eancias espec\u00edficas: entre 9 de dezembro de 2024 a 9 de janeiro 2025, a depender da carreira;<br>Divulga\u00e7\u00e3o do resultado da Fuvest 2024: 24 de janeiro de 2025.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na primeira etapa do processo, os estudantes ter\u00e3o que responder 90 quest\u00f5es de m\u00faltipla escolha O vestibular da Fuvest (Funda\u00e7\u00e3o Universit\u00e1ria para o Vestibular), para ingresso nos cursos de gradua\u00e7\u00e3o da USP (Universidade de S\u00e3o Paulo), come\u00e7a neste domingo (17). De agora em diante, os alunos t\u00eam pouco tempo para revisar os t\u00f3picos mais importantes<\/p>\n","protected":false},"author":1,"featured_media":60687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-60685","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60685"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60685\/revisions"}],"predecessor-version":[{"id":60688,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60685\/revisions\/60688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/60687"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}