{"id":60422,"date":"2024-10-29T05:03:37","date_gmt":"2024-10-29T05:03:37","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=60422"},"modified":"2024-10-29T05:03:38","modified_gmt":"2024-10-29T05:03:38","slug":"universidade-do-canada-oferece-bolsas-de-estudos-de-graduacao","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/10\/29\/universidade-do-canada-oferece-bolsas-de-estudos-de-graduacao\/","title":{"rendered":"Universidade do Canad\u00e1 oferece bolsas de estudos de gradua\u00e7\u00e3o"},"content":{"rendered":"\n<p>Inscri\u00e7\u00f5es para as bolsas est\u00e3o abertas at\u00e9 o dia 15 de novembro<\/p>\n\n\n\n<p>A Universidade da Col\u00fambia Brit\u00e2nica est\u00e1 com inscri\u00e7\u00f5es abertas para bolsas de estudos de gradua\u00e7\u00e3o.<\/p>\n\n\n\n<p>Os candidatos internacionais que desejam estudar na institui\u00e7\u00e3o devem se inscrever no site.<\/p>\n\n\n\n<p>A universidade oferece as bolsas International Major Entrance Scholarship e Outstanding International Student Award.<\/p>\n\n\n\n<p>A primeira \u00e9 prorrog\u00e1vel por at\u00e9 tr\u00eas anos de estudo e concede pr\u00eamios de US$ 10.000 a US$ 20.000 por ano. Para ser aceito, os estudantes devem ingressar diretamente do ensino m\u00e9dio, ter desempenho acad\u00eamico \u201cexcepcional\u201d, envolvimento extracurricular e comunit\u00e1rio, e n\u00e3o ser indicado para um pr\u00eamio baseado em necessidade e m\u00e9rito.<\/p>\n\n\n\n<p>A segunda oportunidade \u00e9 oferecida apenas no primeiro ano. O pr\u00eamio vai de US$ 10.000 a US$ 25.000. Para ser escolhido, o estudante deve demonstrar excelente desempenho acad\u00eamico e forte envolvimento extracurricular, e n\u00e3o pode ter sido indicado para um pr\u00eamio baseado em necessidade e m\u00e9rito.<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es para as bolsas devem ser feitas at\u00e9 o dia 15 de novembro. J\u00e1 as candidaturas para estudar na Universidade devem ser feitas at\u00e9 o dia 1\u00ba de dezembro.<\/p>\n\n\n\n<p>A previs\u00e3o \u00e9 que os resultados saiam entre 15 e 30 de abril de 2025.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es para as bolsas est\u00e3o abertas at\u00e9 o dia 15 de novembro A Universidade da Col\u00fambia Brit\u00e2nica est\u00e1 com inscri\u00e7\u00f5es abertas para bolsas de estudos de gradua\u00e7\u00e3o. Os candidatos internacionais que desejam estudar na institui\u00e7\u00e3o devem se inscrever no site. A universidade oferece as bolsas International Major Entrance Scholarship e Outstanding International Student Award. A<\/p>\n","protected":false},"author":1,"featured_media":60424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-60422","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60422"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60422\/revisions"}],"predecessor-version":[{"id":60425,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60422\/revisions\/60425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/60424"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}