{"id":60332,"date":"2024-10-22T21:07:08","date_gmt":"2024-10-22T21:07:08","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=60332"},"modified":"2024-10-22T21:07:08","modified_gmt":"2024-10-22T21:07:08","slug":"bolsonaro-amplia-aliancas-em-campo-grande-de-olho-na-disputa-pelo-senado-em-2026","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/10\/22\/bolsonaro-amplia-aliancas-em-campo-grande-de-olho-na-disputa-pelo-senado-em-2026\/","title":{"rendered":"Bolsonaro amplia alian\u00e7as em Campo Grande de olho na disputa pelo Senado em 2026"},"content":{"rendered":"\n<p>Uma das metas \u00e9 aumentar a presen\u00e7a da direita entre os senadores<\/p>\n\n\n\n<p>Com o apoio disputado desde o primeiro turno, o ex-presidente Jair Bolsonaro (PL) tra\u00e7ou uma estrat\u00e9gia para ampliar alian\u00e7as e fortalecer candidaturas competitivas ao Senado pelo Mato Grosso do Sul (MS) nas elei\u00e7\u00f5es de 2026.<\/p>\n\n\n\n<p>Uma de suas principais metas \u00e9 aumentar a presen\u00e7a da direita no Senado, Casa que tem a prerrogativa de, entre outras coisas, votar o impeachment de ministros do Supremo Tribunal Federal (STF).<\/p>\n\n\n\n<p>Como parte dessa articula\u00e7\u00e3o, Bolsonaro declarou apoio a Beto Pereira (PSDB) no primeiro turno, que terminou a disputa em terceiro lugar.<\/p>\n\n\n\n<p>De acordo com aliados do ex-presidente, a articula\u00e7\u00e3o para apoiar os tucanos foi costurada com lideran\u00e7as pol\u00edticas do PSDB e do PL. Entre elas, o ex-governador Reinaldo Azambuja (PSDB), atual presidente da legenda no estado.<\/p>\n\n\n\n<p>Azambuja \u00e9 um dos nomes cogitados para disputar uma das duas vagas ao Senado nas pr\u00f3ximas elei\u00e7\u00f5es majorit\u00e1rias. O ex-presidente pode apoiar mais de um candidato no estado em 2026, j\u00e1 que duas vagas estar\u00e3o em disputa, e est\u00e1 avaliando nomes de outras legendas da direita.<\/p>\n\n\n\n<p>A alian\u00e7a com os tucanos no primeiro turno decepcionou a senadora Tereza Cristina (PP-MS), que apoia a candidata \u00e0 reelei\u00e7\u00e3o Adriane Lopes (PP).<\/p>\n\n\n\n<p>No entanto, com Lopes avan\u00e7ando para o segundo turno, Bolsonaro gravou apoio \u00e0 candidata de Tereza Cristina e assim consolidando assim sua alian\u00e7a tamb\u00e9m com o PP.<\/p>\n\n\n\n<p>O PSDB e o PP s\u00e3o os partidos com maior n\u00fameros de prefeitura em Mato Grosso do Sul. Os tucanos t\u00eam 44, dos 78 munic\u00edpios e v\u00e3o contar com o comando das maiores cidades como Dourados e Tr\u00eas Lagoas.<\/p>\n\n\n\n<p>O PP soma 15 prefeituras, j\u00e1 o PL elegeu cinco chefes de executivo no estado.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma das metas \u00e9 aumentar a presen\u00e7a da direita entre os senadores Com o apoio disputado desde o primeiro turno, o ex-presidente Jair Bolsonaro (PL) tra\u00e7ou uma estrat\u00e9gia para ampliar alian\u00e7as e fortalecer candidaturas competitivas ao Senado pelo Mato Grosso do Sul (MS) nas elei\u00e7\u00f5es de 2026. Uma de suas principais metas \u00e9 aumentar a<\/p>\n","protected":false},"author":1,"featured_media":60334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[71],"tags":[],"class_list":{"0":"post-60332","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=60332"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60332\/revisions"}],"predecessor-version":[{"id":60335,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/60332\/revisions\/60335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/60334"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=60332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=60332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=60332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}