{"id":59942,"date":"2024-09-21T02:09:51","date_gmt":"2024-09-21T02:09:51","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=59942"},"modified":"2024-09-21T02:09:52","modified_gmt":"2024-09-21T02:09:52","slug":"governo-bloqueia-mais-r-21-bilhoes-no-orcamento-para-tentar-cumprir-meta-fiscal","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/09\/21\/governo-bloqueia-mais-r-21-bilhoes-no-orcamento-para-tentar-cumprir-meta-fiscal\/","title":{"rendered":"Governo bloqueia mais R$ 2,1 bilh\u00f5es no or\u00e7amento para tentar cumprir meta fiscal"},"content":{"rendered":"\n<p>Somado ao valor bloqueado pelo governo no \u00faltimo relat\u00f3rio, em julho, de R$ 11,2 bilh\u00f5es, o n\u00famero j\u00e1 chega a R$ 13,3 bilh\u00f5es<\/p>\n\n\n\n<p>Os minist\u00e9rios da Fazenda e Planejamento anunciaram um novo bloqueio de R$ 2,1 bilh\u00f5es em despesas discricion\u00e1rias no or\u00e7amento federal nesta sexta-feira (20). O governo tamb\u00e9m reverteu o contingenciamento de R$ 3,8 bilh\u00f5es feito em julho. Os n\u00fameros constam no relat\u00f3rio de avalia\u00e7\u00e3o de receitas e despesas referente ao quarto bimestre.<\/p>\n\n\n\n<p>Com a revers\u00e3o do contingenciamento, o valor total congelado em julho, de R$ 15 bilh\u00f5es, caiu para R$ 13,3 bilh\u00f5es.<\/p>\n\n\n\n<p>A equipe econ\u00f4mica dar\u00e1 uma coletiva de imprensa para tirar d\u00favidas na segunda-feira (23), mas o decreto com detalhamento de quais minist\u00e9rios ser\u00e3o afetados s\u00f3 ser\u00e1 divulgado no dia 30 deste m\u00eas.<\/p>\n\n\n\n<p>O bloqueio de despesas discricion\u00e1rias acontece quando as despesas obrigat\u00f3rias ultrapassam o teto previsto pelo arcabou\u00e7o fiscal: de 70% do crescimento da receita acima da infla\u00e7\u00e3o.<\/p>\n\n\n\n<p>J\u00e1 o contingenciamento ocorre quando h\u00e1 descasamento entre as receitas e as despesas previstas para o ano e o d\u00e9bito ultrapassa as receitas e compromete a meta fiscal do governo.<\/p>\n\n\n\n<p>De acordo com o documento do quarto bimestre, enviado nesta sexta ao Congresso Nacional, o d\u00e9ficit prim\u00e1rio estimado para 2024 agora \u00e9 de R$ 28,3 bilh\u00f5es, dentro do limite superior de 0,25% do Produto Interno Bruto (PIB) para o governo conseguir atingir a meta de zerar o rombo das contas p\u00fablicas, ou seja deixar os gastos em linha com o que entra no caixa do Tesouro Nacional.<\/p>\n\n\n\n<p>Em julho, o rombo era de R$ 32,6 bilh\u00f5es, equivalente a 0,3% do PIB. Mas, segundo a equipe econ\u00f4mica, houve um aumento de R$ 4,4 bilh\u00f5es nos cofres p\u00fablicos e um crescimento menor nas despesas prim\u00e1rias entre julho e agosto, o que proporcionou a revis\u00e3o do contingenciamento e manter as contas em trajet\u00f3ria para terminar o ano no azul.<\/p>\n\n\n\n<p>De acordo com a equipe econ\u00f4mica, os principais fatores que levaram ao aumento das despesas obrigat\u00f3rias, justificando o novo bloqueio de R$ 2,1 bilh\u00f5es, foram os seguintes:<\/p>\n\n\n\n<p>Aumento de R$ 5,3 bilh\u00f5es em benef\u00edcios previdenci\u00e1rios, em especial com rela\u00e7\u00e3o a pleitos vencidos em processos judiciais sobre benef\u00edcios previdenci\u00e1rios, como aposentadorias ou pens\u00f5es.<\/p>\n\n\n\n<p>Atrelado a isso, um aumento de mais de R$ 300 milh\u00f5es em Benef\u00edcios de Presta\u00e7\u00e3o Continuada (BPC). Mas, segundo a equipe econ\u00f4mica, o governo tamb\u00e9m conseguiu economizar cerca de R$ 500 milh\u00f5es ao revisar os cadastros das pessoas que recebem o benef\u00edcio.<\/p>\n\n\n\n<p>A possibilidade de bloqueio j\u00e1 havia sido antecipada no come\u00e7o do m\u00eas pelo secret\u00e1rio do Tesouro Nacional, Rog\u00e9rio Ceron, que relatou uma \u201cpress\u00e3o adicional\u201d nas contas p\u00fablicas causada pelos benef\u00edcios assistenciais.<\/p>\n\n\n\n<p>Os valores tamb\u00e9m foram parcialmente compensados pela redu\u00e7\u00e3o de algumas despesas, como desembolsos para a Pol\u00edtica Aldir Blanc, de Fomento \u00e0 Cultura, em R$ 1,9 bilh\u00e3o; desembolso com pessoal na justi\u00e7a, em R$ 1 bilh\u00e3o e R$ 0,9 bilh\u00e3o em senten\u00e7as judiciais e precat\u00f3rios.<\/p>\n\n\n\n<p>Para evitar que o mesmo ocorra em 2025, o governo planeja uma tesourada de R$ 25,9 bilh\u00f5es mirando Previd\u00eancia, Bolsa Fam\u00edlia, Proagro e Seguro Defeso. Al\u00e9m disso, a equipe econ\u00f4mica tamb\u00e9m quer enxugar gastos menores em minist\u00e9rios e realocar em outros programas.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Somado ao valor bloqueado pelo governo no \u00faltimo relat\u00f3rio, em julho, de R$ 11,2 bilh\u00f5es, o n\u00famero j\u00e1 chega a R$ 13,3 bilh\u00f5es Os minist\u00e9rios da Fazenda e Planejamento anunciaram um novo bloqueio de R$ 2,1 bilh\u00f5es em despesas discricion\u00e1rias no or\u00e7amento federal nesta sexta-feira (20). O governo tamb\u00e9m reverteu o contingenciamento de R$ 3,8<\/p>\n","protected":false},"author":1,"featured_media":59943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-59942","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59942"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59942\/revisions"}],"predecessor-version":[{"id":59945,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59942\/revisions\/59945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/59943"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}