{"id":59937,"date":"2024-09-21T02:07:38","date_gmt":"2024-09-21T02:07:38","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=59937"},"modified":"2024-09-21T02:07:39","modified_gmt":"2024-09-21T02:07:39","slug":"agu-e-cgu-concluem-acordos-de-leniencia-com-empresas-da-lava-jato","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/09\/21\/agu-e-cgu-concluem-acordos-de-leniencia-com-empresas-da-lava-jato\/","title":{"rendered":"AGU e CGU concluem acordos de leni\u00eancia com empresas da Lava Jato"},"content":{"rendered":"\n<p>Acordo foi enviado ao Supremo Tribunal Federal (STF); a concilia\u00e7\u00e3o entre a Uni\u00e3o e as empresas foi aberta pelo ministro Andr\u00e9 Mendon\u00e7a, relator do caso<\/p>\n\n\n\n<p>A Advocacia-geral da Uni\u00e3o (AGU) e a Controladoria-Geral da Uni\u00e3o (CGU) entregaram nesta sexta-feira (20) ao Supremo Tribunal Federal (STF) a proposta final do acordo de leni\u00eancia com as empresas envolvidas no \u00e2mbito da Opera\u00e7\u00e3o Lava Jato.<\/p>\n\n\n\n<p>A concilia\u00e7\u00e3o entre a Uni\u00e3o e as empresas foi aberta pelo ministro Andr\u00e9 Mendon\u00e7a, relator do caso apresentado em 2023 pelos partidos PSOL, PCdoB e Solidariedade na Suprema Corte. As siglas questionam os par\u00e2metros adotados nos acordos anteriores com as empresas.<\/p>\n\n\n\n<p>As sete companhias que dever\u00e3o firmar termos aditivos aos acordos de leni\u00eancia previamente celebrados com a Uni\u00e3o s\u00e3o as seguintes:<\/p>\n\n\n\n<p>UTC Participa\u00e7\u00f5es S.A.;<br>Braskem S.A.;<br>OAS (atual Metha);<br>Camargo Corr\u00eaa;<br>Andrade Gutierrez;<br>Nova Participa\u00e7\u00f5es S.A.<br>e Odebrecht (atual Novonor).<br>Em valores atualizados, essas empresas ainda devem R$ 11,8 bilh\u00f5es \u00e0 Uni\u00e3o e est\u00e3o inadimplentes. A Uni\u00e3o apresentou uma f\u00f3rmula que prev\u00ea abatimento de at\u00e9 50% no saldo devedor.<\/p>\n\n\n\n<p>Para chegar ao abatimento de 50%, o governo abriu m\u00e3o da cobran\u00e7a de juros sobre parcelas atrasadas e permitiu a amplia\u00e7\u00e3o do uso do preju\u00edzo fiscal das empreiteiras. Elas acumularam cr\u00e9ditos tribut\u00e1rios, por dedu\u00e7\u00f5es n\u00e3o utilizadas do Imposto de Renda de Pessoa Jur\u00eddica (IRPJ), diante do preju\u00edzo verificado nos \u00faltimos anos.<\/p>\n\n\n\n<p>Os cr\u00e9ditos de preju\u00edzo fiscal que ultrapassarem 50% do saldo devedor de cada empresa n\u00e3o poder\u00e3o ser usados.<\/p>\n\n\n\n<p>Os termos dos aditivos decorrentes da concilia\u00e7\u00e3o s\u00e3o os mesmos que haviam sido informados ao ministro-relator em agosto deste ano, quando a AGU e CGU pediram ao STF a prorroga\u00e7\u00e3o do prazo com o objetivo de finalizar os \u00faltimos aspectos das negocia\u00e7\u00f5es:<\/p>\n\n\n\n<p>isen\u00e7\u00e3o da multa morat\u00f3ria de 2% incidente sobre as parcelas vencidas das d\u00edvidas das empresas;<br>substitui\u00e7\u00e3o do Sistema Especial de Liquida\u00e7\u00e3o e de Cust\u00f3dia (Selic) pelo \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA) como indexador do saldo devedor das empresas no \u00e2mbito dos acordos at\u00e9 a data de 31\/05\/2024. A Selic permanece como indexador ap\u00f3s a celebra\u00e7\u00e3o dos termos aditivos ao acordo;<br>a possibilidade de utiliza\u00e7\u00e3o, pelas empresas, de cr\u00e9ditos de preju\u00edzo fiscal e de base de c\u00e1lculo negativa da Contribui\u00e7\u00e3o Social sobre o Lucro L\u00edquido (CSLL), na apura\u00e7\u00e3o do Imposto sobre a Renda das Pessoas Jur\u00eddicas (IRPJ) e da CSLL, limitada aos casos em que, ap\u00f3s an\u00e1lise, o d\u00e9bito da empresa se enquadre na situa\u00e7\u00e3o de dif\u00edcil recupera\u00e7\u00e3o financeira;<br>renegocia\u00e7\u00e3o do perfil de pagamento (cronograma de pagamento), de acordo com a capacidade de pagamento das empresas.<br>O acordo prev\u00ea, ainda, um abatimento de valores devolvidos por delatores dos esquemas de corrup\u00e7\u00e3o da Lava Jato. Alguns deles, em seus acordos de colabora\u00e7\u00e3o premiada, aceitaram entregar recursos obtidos ilegalmente.<\/p>\n\n\n\n<p>Nos casos em que a devolu\u00e7\u00e3o tiver sido feita por ex-executivos das empreiteiras (e n\u00e3o das estatais lesadas), o valor poder\u00e1 ser abatido dos acordos de leni\u00eancia.<\/p>\n\n\n\n<p>Segundo a AGU, as principais diretrizes levadas em considera\u00e7\u00e3o nas tratativas que foram encaminhadas ao STF foram:<\/p>\n\n\n\n<p>a continuidade da atividade econ\u00f4mica, com a preserva\u00e7\u00e3o e a gera\u00e7\u00e3o de empregos na constru\u00e7\u00e3o civil, setor estrat\u00e9gico para o desenvolvimento nacional;<br>a preserva\u00e7\u00e3o da agenda de integridade p\u00fablica, com a manuten\u00e7\u00e3o dos acordos de leni\u00eancia vigentes; e<br>o fortalecimento do mecanismo da consensualidade para supera\u00e7\u00e3o dos conflitos no Judici\u00e1rio.<br>Agora caber\u00e1 ao STF a an\u00e1lise da proposta e sua eventual homologa\u00e7\u00e3o. Ap\u00f3s essa etapa, se homologados, os termos aditivos passam a vigorar e as empresas voltar\u00e3o a pagar as parcelas dos acordos j\u00e1 sob a sistem\u00e1tica definida por meio dos aditivos.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acordo foi enviado ao Supremo Tribunal Federal (STF); a concilia\u00e7\u00e3o entre a Uni\u00e3o e as empresas foi aberta pelo ministro Andr\u00e9 Mendon\u00e7a, relator do caso A Advocacia-geral da Uni\u00e3o (AGU) e a Controladoria-Geral da Uni\u00e3o (CGU) entregaram nesta sexta-feira (20) ao Supremo Tribunal Federal (STF) a proposta final do acordo de leni\u00eancia com as empresas<\/p>\n","protected":false},"author":1,"featured_media":59939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[71],"tags":[],"class_list":{"0":"post-59937","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59937"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59937\/revisions"}],"predecessor-version":[{"id":59940,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59937\/revisions\/59940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/59939"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}