{"id":59553,"date":"2024-09-07T04:56:55","date_gmt":"2024-09-07T04:56:55","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=59553"},"modified":"2024-09-07T04:56:56","modified_gmt":"2024-09-07T04:56:56","slug":"em-pronunciamento-sobre-7-de-setembro-lula-defende-democracia-nossa-soberania-nao-esta-a-venda","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/09\/07\/em-pronunciamento-sobre-7-de-setembro-lula-defende-democracia-nossa-soberania-nao-esta-a-venda\/","title":{"rendered":"Em pronunciamento sobre 7 de Setembro, Lula defende democracia: \u201cNossa soberania n\u00e3o est\u00e1 \u00e0 venda\u201d"},"content":{"rendered":"\n<p>Presidente ressaltou a import\u00e2ncia do debate entre opini\u00f5es diferentes, do di\u00e1logo e da \u201cconviv\u00eancia civilizada entre opostos<\/p>\n\n\n\n<p>O presidente Luiz In\u00e1cio Lula da Silva (PT) afirmou, nesta sexta-feira (6), que \u201cnenhum pa\u00eds \u00e9 independente sem o exerc\u00edcio supremo da democracia\u201d.<\/p>\n\n\n\n<p>A declara\u00e7\u00e3o foi feita em pronunciamento em rede nacional nesta noite, em alus\u00e3o ao Dia da Independ\u00eancia, comemorado no s\u00e1bado (7).<\/p>\n\n\n\n<p>Amanh\u00e3 \u00e9 dia de comemorarmos a independ\u00eancia do Brasil. E \u00e9 tamb\u00e9m um bom momento para celebrarmos a democracia. Nenhum pa\u00eds \u00e9 de fato independente sem o exerc\u00edcio pleno da democracia<\/p>\n\n\n\n<p>Luiz In\u00e1cio Lula da Silva<br>Durante o pronunciamento, Lula ressaltou a import\u00e2ncia do debate entre opini\u00f5es diferentes, do di\u00e1logo e da \u201cconviv\u00eancia civilizada entre opostos\u201d. O presidente mencionou momentos de uni\u00e3o entre pol\u00edticos de diferentes campos pol\u00edticos ao longo de seu mandato.<\/p>\n\n\n\n<p>\u201cEm momentos decisivos da hist\u00f3ria, a defesa da democracia \u00e9 capaz de unir advers\u00e1rios de longa data. Foi assim na constru\u00e7\u00e3o da alian\u00e7a para garantir a governabilidade do pa\u00eds, ap\u00f3s as elei\u00e7\u00f5es de 2022. Foi assim no 8 de janeiro de 2023, quando democratas de quase todos os partidos se uniram para derrotar a tentativa de golpe\u201d, disse o presidente.<\/p>\n\n\n\n<p>\u201cNenhum pa\u00eds \u00e9 de fato independente quando tolera amea\u00e7as \u00e0 sua soberania. Seremos sempre intolerantes com qualquer pessoa, tenha a fortuna que tiver, que desafie a legisla\u00e7\u00e3o brasileira. Nossa soberania n\u00e3o est\u00e1 \u00e0 venda. Nenhum pa\u00eds do mundo \u00e9 de fato independente quando seu povo perde a esperan\u00e7a. Por isso, comemoramos a volta da capacidade de sonhar da nossa juventude, gra\u00e7as \u00e0 gera\u00e7\u00e3o de oportunidades para todos e todas\u201d, continuou o mandat\u00e1rio.<\/p>\n\n\n\n<p>Lula tamb\u00e9m afirmou que democracia \u00e9 \u201cmais que votar no dia da elei\u00e7\u00e3o\u201d. \u201c\u00c9 lutar pela conquista de direitos\u201d, disse o presidente. Ele citou a\u00e7\u00f5es sociais nas \u00e1reas de moradia, emprego, renda e alimenta\u00e7\u00e3o, al\u00e9m das obras do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC).<\/p>\n\n\n\n<p>Dia da Independ\u00eancia<br>A Esplanada dos Minist\u00e9rios recebe na manh\u00e3 de s\u00e1bado o tradicional desfile c\u00edvico-militar em celebra\u00e7\u00e3o ao Dia da Independ\u00eancia. Aberto ao p\u00fablico, o evento contar\u00e1 com arquibancadas no Eixo Monumental.<\/p>\n\n\n\n<p>O acesso ao local ser\u00e1 liberado \u00e0s 6h20, e o tr\u00e2nsito na Esplanada estar\u00e1 fechado. De acordo com a Secretaria de Comunica\u00e7\u00e3o da Presid\u00eancia da Rep\u00fablica (Secom), o in\u00edcio do desfile est\u00e1 previsto para \u00e0s 8h45, com a chegada do presidente Lula e a revista \u00e0s tropas.<\/p>\n\n\n\n<p>O desfile contar\u00e1 com a presen\u00e7a de alunos de escolas p\u00fablicas do Distrito Federal, atletas que representaram o Brasil nas Olimp\u00edadas e de militares das For\u00e7as Armadas. Al\u00e9m disso, haver\u00e1 apresenta\u00e7\u00e3o da Pir\u00e2mide Humana do Batalh\u00e3o de Pol\u00edcia do Ex\u00e9rcito e performance da Esquadrilha da Fuma\u00e7a.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidente ressaltou a import\u00e2ncia do debate entre opini\u00f5es diferentes, do di\u00e1logo e da \u201cconviv\u00eancia civilizada entre opostos O presidente Luiz In\u00e1cio Lula da Silva (PT) afirmou, nesta sexta-feira (6), que \u201cnenhum pa\u00eds \u00e9 independente sem o exerc\u00edcio supremo da democracia\u201d. A declara\u00e7\u00e3o foi feita em pronunciamento em rede nacional nesta noite, em alus\u00e3o ao Dia<\/p>\n","protected":false},"author":1,"featured_media":59555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[71],"tags":[],"class_list":{"0":"post-59553","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59553"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59553\/revisions"}],"predecessor-version":[{"id":59556,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59553\/revisions\/59556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/59555"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}