{"id":59216,"date":"2024-08-25T11:02:19","date_gmt":"2024-08-25T11:02:19","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=59216"},"modified":"2024-08-25T11:02:20","modified_gmt":"2024-08-25T11:02:20","slug":"bolsa-sobe-12-na-semana-apos-sequencia-de-recordes-dolar-vai-a-r-547","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2024\/08\/25\/bolsa-sobe-12-na-semana-apos-sequencia-de-recordes-dolar-vai-a-r-547\/","title":{"rendered":"Bolsa sobe 1,2% na semana ap\u00f3s sequ\u00eancia de recordes; d\u00f3lar vai a R$ 5,47"},"content":{"rendered":"\n<p>Presidente do banco central americano disse que &#8220;chegou a hora&#8221; de cortar os juros nos EUA<\/p>\n\n\n\n<p>O Ibovespa retomava o vi\u00e9s positivo nesta sexta-feira (23), recuperandando a queda da \u00faltima sess\u00e3o ap\u00f3s o presidente do Federal Reserve, Jerome Powell, afirmar que \u201cchegou a hora\u201d de o banco central dos Estados Unidos cortar os juros. Na semana, a bolsa acumula ganho superior a 1%, depois de uma sequ\u00eancia de recordes.<\/p>\n\n\n\n<p>O Ibovespa fechou em moderada alta de 0,32%, a 135.608,47 pontos. Na v\u00e9spera, o Ibovespa caiu quase 1%, em dia de realiza\u00e7\u00e3o de lucros, ap\u00f3s renovar m\u00e1ximas hist\u00f3ricas nos preg\u00f5es anteriores. Com o desempenho desta sexta-feira, acumula na semana um ganho de 1,23%, ampliando o de agosto para 6,23%.<\/p>\n\n\n\n<p>J\u00e1 o d\u00f3lar encerrou a sess\u00e3o em baixa de 1,97%, cotado a R$ 5,479. Mesmo assim, na semana a moeda acumula alta de 0,22%.<\/p>\n\n\n\n<p>O rali recente na bolsa paulista tem como suporte o fluxo de capital externo, com uma entrada l\u00edquida de R$ 7 bilh\u00f5es em agosto at\u00e9 o dia 21, estimulada principalmente pelo aumento das apostas na redu\u00e7\u00e3o dos juros norte-americanos.<\/p>\n\n\n\n<p>Nesta sexta-feira, Powell possivelmente eliminou qualquer d\u00favida que ainda pudesse pairar nas mesas de negocia\u00e7\u00f5es ao afirmar que \u201cchegou a hora de ajustar a pol\u00edtica (monet\u00e1ria)\u201d norte-americana.<\/p>\n\n\n\n<p>\u201cA dire\u00e7\u00e3o a ser seguida \u00e9 clara, e o momento e o ritmo dos cortes nos juros depender\u00e3o dos dados que chegarem, da evolu\u00e7\u00e3o das perspectivas e do equil\u00edbrio dos riscos\u201d, afirmou no tradicional simp\u00f3sio de Jackson Hole.<\/p>\n\n\n\n<p>Falando sobre as duas metas que o Fed \u00e9 encarregado pelo Congresso de atingir, Powell disse que sua \u201cconfian\u00e7a cresceu de que a infla\u00e7\u00e3o est\u00e1 em um caminho sustent\u00e1vel de volta para 2%\u201d, enquanto o desemprego est\u00e1 aumentando.<\/p>\n\n\n\n<p>Na vis\u00e3o do economista Francisco Nobre, da XP, as apostas j\u00e1 sinalizavam que o Fed come\u00e7aria o ciclo de flexibiliza\u00e7\u00e3o monet\u00e1ria na reuni\u00e3o de setembro, mas sem consenso se iniciando com um corte de 0,25 ou de 0,50 ponto percentual.<\/p>\n\n\n\n<p>\u201cNesse sentido, o discurso dele (de Powell) deixou essas duas possibilidades bastante em aberto\u201d, avaliou.<\/p>\n\n\n\n<p>Para Nobre, dada a \u00eanfase de Powell de que o Fed n\u00e3o tolerar\u00e1 um enfraquecimento adicional do mercado de trabalho, o pr\u00f3ximo relat\u00f3rio de emprego, previsto para 6 de setembro, pode ser decisivo para consolidar as apostas sobre o ritmo do corte.<\/p>\n\n\n\n<p>O Comit\u00ea Federal de Mercado Aberto (Fomc) do Fed se reunir\u00e1 nos dias 17 e 18 de setembro para decidir sobre os juros, atualmente na faixa de 5,25% a 5,50%, com a decis\u00e3o sendo conhecida no segundo dia do encontro.<\/p>\n\n\n\n<p>Em Wall Street, o S&amp;P 500, uma das refer\u00eancias do mercado acion\u00e1rio norte-americano, fechou em alta de 1,15%, enquanto o rendimento do t\u00edtulo de 10 anos Tesouro dos EUA marcava 3,799% no final da tarde, de 3,862% na v\u00e9spera.<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidente do banco central americano disse que &#8220;chegou a hora&#8221; de cortar os juros nos EUA O Ibovespa retomava o vi\u00e9s positivo nesta sexta-feira (23), recuperandando a queda da \u00faltima sess\u00e3o ap\u00f3s o presidente do Federal Reserve, Jerome Powell, afirmar que \u201cchegou a hora\u201d de o banco central dos Estados Unidos cortar os juros. Na<\/p>\n","protected":false},"author":1,"featured_media":59218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-59216","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=59216"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59216\/revisions"}],"predecessor-version":[{"id":59219,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/59216\/revisions\/59219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/59218"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=59216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=59216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=59216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}