{"id":52869,"date":"2023-10-21T17:12:38","date_gmt":"2023-10-21T17:12:38","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=52869"},"modified":"2023-10-21T17:12:39","modified_gmt":"2023-10-21T17:12:39","slug":"desmatamento-dobrou-no-cerrado-em-setembro-diz-instituto","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/10\/21\/desmatamento-dobrou-no-cerrado-em-setembro-diz-instituto\/","title":{"rendered":"Desmatamento dobrou no Cerrado em setembro, diz instituto"},"content":{"rendered":"\n<p>Bioma brasileiro perdeu mais de 83 mil hectares apenas no m\u00eas; acumulado anual ultrapassa 742 mil hectares<\/p>\n\n\n\n<p>O desmatamento no Cerrado cresceu 60,5% em setembro deste ano em compara\u00e7\u00e3o com o mesmo m\u00eas de 2022.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o \u00e9 do Sistema de Alerta de Desmatamento do Cerrado(SAD-Cerrado), que foi atualizado, nesta quinta-feira (19), pelo Instituto de Pesquisa Ambiental da Amaz\u00f4nia (Ipam) com base em imagens obtidas via sat\u00e9lite da Ag\u00eancia Espacial Europeia.<\/p>\n\n\n\n<p>De acordo com o monitoramento, a \u00e1rea afetada em setembro de 2023 \u00e9 de 83 mil hectares. Em 2022, foram registrados 51,4 mil. O dado de 2023 representa 242% mais do que o registrado dois anos atr\u00e1s, em setembro, em 2021.<\/p>\n\n\n\n<p>Com setembro, o acumulado de desmatamento do Cerrado no Brasil em 2023 chega a 742 hectares. Esse n\u00famero representa aumento de 20,9% em rela\u00e7\u00e3o ao registrado no mesmo per\u00edodo em 2022, de 613.274 hectares.<\/p>\n\n\n\n<p>\u00c1rea mais afetada \u00e9 no Matopiba<br>\u201cMatopiba\u201d \u00e9 o nome de uma \u00e1rea de cultivo de gr\u00e3os que engloba cidades dos estados do Maranh\u00e3o, Tocantins, Piau\u00ed e Bahia. E foi exatamente essa \u00e1rea que concentrou o desmatamento no Cerrado em setembro de 2023.<\/p>\n\n\n\n<p>Dos 83 mil hectares de vegeta\u00e7\u00e3o nativa derrubados, 62,2 mil \u2014 ou seja, cerca de 75% \u2014 foram no Matopiba.<\/p>\n\n\n\n<p>Dos dez munic\u00edpios com maior n\u00famero de alertas, nove est\u00e3o no Maranh\u00e3o. J\u00e1 em rela\u00e7\u00e3o \u00e0s cidades com maior \u00e1rea desmatada, as tr\u00eas primeiras est\u00e3o na Bahia, enquanto outras quatro est\u00e3o no Maranh\u00e3o, uma no Tocantins e outra no Piau\u00ed.<\/p>\n\n\n\n<p>Al\u00e9m do Matopiba<br>O Matopiba concentrou a maior \u00e1rea desmatada, e, enquanto isso, outros estados tamb\u00e9m contabilizaram aumento na devasta\u00e7\u00e3o do bioma. Minas Gerais \u00e9 um dos destaques como o primeiro estado fora da regi\u00e3o a aparecer no ranking de unidades de federa\u00e7\u00e3o com maior desmatamento do Cerrado.<\/p>\n\n\n\n<p>Segundo o Ipam, foram derrubados 5,3 mil hectares no bioma no estado mineiro em setembro de 2023. Esse dado representa 140% mais do que o registrado no mesmo m\u00eas no ano passado. O acumulado anual de 2023 j\u00e1 supera 46,2 mil hectares.<\/p>\n\n\n\n<p>Em seguida, est\u00e3o Goi\u00e1s (4,1 mil hectares em setembro de 2023), Mato Grosso (3,3 mil hectares) e Mato Grosso do Sul (3,1 mil hectares).<\/p>\n\n\n\n<p>Fonte: CNN Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bioma brasileiro perdeu mais de 83 mil hectares apenas no m\u00eas; acumulado anual ultrapassa 742 mil hectares O desmatamento no Cerrado cresceu 60,5% em setembro deste ano em compara\u00e7\u00e3o com o mesmo m\u00eas de 2022. A informa\u00e7\u00e3o \u00e9 do Sistema de Alerta de Desmatamento do Cerrado(SAD-Cerrado), que foi atualizado, nesta quinta-feira (19), pelo Instituto de<\/p>\n","protected":false},"author":1,"featured_media":52871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-52869","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=52869"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52869\/revisions"}],"predecessor-version":[{"id":52872,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/52869\/revisions\/52872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/52871"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=52869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=52869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=52869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}