{"id":49372,"date":"2023-05-15T14:20:35","date_gmt":"2023-05-15T14:20:35","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/?p=49372"},"modified":"2023-05-15T14:20:36","modified_gmt":"2023-05-15T14:20:36","slug":"secretario-de-tarcisio-planeja-mudar-sede-da-educacao-do-centro-de-sp-para-a-faria-lima","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/05\/15\/secretario-de-tarcisio-planeja-mudar-sede-da-educacao-do-centro-de-sp-para-a-faria-lima\/","title":{"rendered":"Secret\u00e1rio de Tarc\u00edsio planeja mudar sede da Educa\u00e7\u00e3o do centro de SP para a Faria Lima"},"content":{"rendered":"\n<p>Proposta vai na contram\u00e3o de plano do governador de levar toda a estrutura da gest\u00e3o para a regi\u00e3o central<\/p>\n\n\n\n<p>Na contram\u00e3o do projeto do governador Tarc\u00edsio de Freitas (Republicanos) de revitalizar o centro de S\u00e3o Paulo, o secret\u00e1rio de Educa\u00e7\u00e3o, Renato Feder, planeja mudar a sede da pasta do tradicional pr\u00e9dio que ocupa h\u00e1 45 anos na pra\u00e7a da Rep\u00fablica para a regi\u00e3o da avenida Faria Lima, na zona oeste.<\/p>\n\n\n\n<p>O plano de Feder, que \u00e9 empres\u00e1rio da \u00e1rea de tecnologia, tem sido alvo de cr\u00edticas de integrantes do governo pela escolha de um im\u00f3vel imponente e com aluguel caro fora da regi\u00e3o central.<\/p>\n\n\n\n<p>H\u00e1 ainda a preocupa\u00e7\u00e3o de que a desocupa\u00e7\u00e3o do pr\u00e9dio na pra\u00e7a da Rep\u00fablica possa agravar ainda mais a degrada\u00e7\u00e3o da regi\u00e3o central.<\/p>\n\n\n\n<p>A Folha apurou que a equipe de Feder tem sondado atrav\u00e9s de uma consultoria imobili\u00e1ria a loca\u00e7\u00e3o do edif\u00edcio Eldorado Business Tower, na avenida Na\u00e7\u00f5es Unidas, em Pinheiros. Tido como um dos pr\u00e9dios comerciais mais modernos de S\u00e3o Paulo e de alto padr\u00e3o, tem 32 andares e \u00e9 cercado de vidros brancos serigrafados. Tem piso de granito e detalhes em inox.<\/p>\n\n\n\n<p>O edif\u00edcio foi inaugurado em 2007 e est\u00e1 dentro do terreno do Shopping Eldorado, na zona oeste. O prov\u00e1vel novo endere\u00e7o \u00e9 bem diferente da Casa Caetano de Campos, de estilo neocl\u00e1ssico e projetado pelo arquiteto Ramos de Azevedo no come\u00e7o de 1890.<\/p>\n\n\n\n<p>A sede atual da pasta \u00e9 um dos pr\u00e9dios mais emblem\u00e1ticos da educa\u00e7\u00e3o de S\u00e3o Paulo. Inaugurado em agosto de 1894, o edif\u00edcio foi constru\u00eddo para sediar a primeira Escola Normal paulista, que oferecia o equivalente ao ensino b\u00e1sico atual.<\/p>\n\n\n\n<p>A Casa Caetano de Campos tamb\u00e9m \u00e9 considerada um dos ber\u00e7os da USP (Universidade de S\u00e3o Paulo), j\u00e1 que, em 1934, o edif\u00edcio foi reformado para abrigar as primeiras turmas da Faculdade de Filosofia, Ci\u00eancias e Letras da institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>De acordo com a consultora imobili\u00e1ria SiiLA, o pre\u00e7o m\u00e9dio do metro quadrado do Eldorado Business \u00e9 de R$ 166,066, acima inclusive da m\u00e9dia na regi\u00e3o.<\/p>\n\n\n\n<p>&#8220;Classificado como um A+ [o mais alto grau de classifica\u00e7\u00e3o], o im\u00f3vel fica na regi\u00e3o de Pinheiros e tem \u00e1rea privativa total de 59.278 m\u00b2. A regi\u00e3o de Pinheiros tem um total de 18 pr\u00e9dios corporativos de alto padr\u00e3o (A+ e A), onde o pre\u00e7o m\u00e9dio pedido por m\u00b2 \u00e9 de 140,92 reais&#8221;, afirma a SiiLA, que faz mapeamentos de escrit\u00f3rios corporativos como o pr\u00f3prio Eldorado Business.<\/p>\n\n\n\n<p>\u00c0 Folha, a Secretaria de Educa\u00e7\u00e3o confirmou que analisa a possibilidade de mudan\u00e7a tempor\u00e1ria da pra\u00e7a da Rep\u00fablica j\u00e1 que um laudo emitido pela FDE (Funda\u00e7\u00e3o para o Desenvolvimento da Educa\u00e7\u00e3o), autarquia ligada \u00e0 pasta, aponta que o pr\u00e9dio necessita de &#8220;reformas estruturais&#8221;.<\/p>\n\n\n\n<p>&#8220;A constru\u00e7\u00e3o tombada apresenta problemas em sua estrutura, especialmente no telhado, parte el\u00e9trica, ar-condicionado e na fachada. De acordo com o laudo, esses problemas podem oferecer riscos aos servidores e ao p\u00fablico que frequentam o im\u00f3vel&#8221;, afirmou a pasta.<\/p>\n\n\n\n<p>A reportagem solicitou acesso ao laudo, mas a secretaria n\u00e3o forneceu o documento.<\/p>\n\n\n\n<p>Em 2019, no primeiro ano da gest\u00e3o Jo\u00e3o Doria (PSDB), uma empresa de engenharia foi contratada por R$ 7,2 milh\u00f5es para reformar o pr\u00e9dio.<\/p>\n\n\n\n<p>A Apeoesp, principal sindicato dos professores estaduais paulistas, criticou o plano do secret\u00e1rio e destacou que a mudan\u00e7a da sede para a regi\u00e3o da Faria Lima ir\u00e1 dificultar o acesso dos profissionais da educa\u00e7\u00e3o, estudantes e pais aos servi\u00e7os da secretaria.<\/p>\n\n\n\n<p>&#8220;[A mudan\u00e7a] para uma regi\u00e3o onde ficam as sedes de bancos e empresas (sendo ele mesmo um empres\u00e1rio), mostra o tipo de prioridades que passa pela cabe\u00e7a deste senhor&#8221;, disse Izabel Noronha, presidente da Apeoesp.<\/p>\n\n\n\n<p>&#8220;A pra\u00e7a da Rep\u00fablica fica no centro, ao lado do metr\u00f4, com acesso f\u00e1cil a popula\u00e7\u00e3o. O que pretende o secret\u00e1rio com essa mudan\u00e7a? Dificultar o acesso, para n\u00e3o ser incomodado. N\u00e3o vai conseguir, porque n\u00e3o permitiremos. A Pra\u00e7a da Rep\u00fablica \u00e9 territ\u00f3rio de nossas lutas e mobiliza\u00e7\u00f5es. E vai continuar sendo.&#8221;<\/p>\n\n\n\n<p>A prov\u00e1vel debandada da pra\u00e7a da Rep\u00fablica tamb\u00e9m causou estranheza na gest\u00e3o Tarc\u00edsio, que na campanha eleitoral se comprometeu a levar a sede do governo paulista do Morumbi, na zona sul, para o Campos El\u00edseos, no centro.<\/p>\n\n\n\n<p>Esse projeto de mudan\u00e7a \u00e9 conduzido pelo secret\u00e1rio de Projetos Estrat\u00e9gicos, Guilherme Afif Domingos.<\/p>\n\n\n\n<p>A mudan\u00e7a serviria exatamente como catalisador de uma revitaliza\u00e7\u00e3o da regi\u00e3o central, que atualmente sofre com uma alta da viol\u00eancia e com a cracol\u00e2ndia.<\/p>\n\n\n\n<p>A Secret\u00e1ria de Educa\u00e7\u00e3o \u00e9 uma das pastas que deveriam migrar para essa nova sede do governo.<\/p>\n\n\n\n<p>A proposta ainda \u00e9 incipiente. A Fipe (Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas) come\u00e7ar\u00e1 na semana que vem o estudo de viabilidade urban\u00edstica. O documento dever\u00e1 ficar pronto dentro de seis meses.<\/p>\n\n\n\n<p>Depois disso, o governo precisaria desapropriar e demolir edifica\u00e7\u00f5es para dar lugar aos mais de 320 mil metros quadrados de \u00e1rea constru\u00edda, com escrit\u00f3rios de reparti\u00e7\u00f5es p\u00fablicas que abrigar\u00e3o 24 mil funcion\u00e1rios.<\/p>\n\n\n\n<p>A gest\u00e3o Tarc\u00edsio estima que os gastos com as desapropria\u00e7\u00f5es podem chegar a R$ 500 milh\u00f5es. A iniciativa privada, ent\u00e3o, ser\u00e1 respons\u00e1vel por construir e administrar os pr\u00e9dios, enquanto o estado pagaria pelas obras ao longo de tr\u00eas d\u00e9cadas.<\/p>\n\n\n\n<p>Fonte: Folha de S.Paulo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proposta vai na contram\u00e3o de plano do governador de levar toda a estrutura da gest\u00e3o para a regi\u00e3o central Na contram\u00e3o do projeto do governador Tarc\u00edsio de Freitas (Republicanos) de revitalizar o centro de S\u00e3o Paulo, o secret\u00e1rio de Educa\u00e7\u00e3o, Renato Feder, planeja mudar a sede da pasta do tradicional pr\u00e9dio que ocupa h\u00e1 45<\/p>\n","protected":false},"author":1,"featured_media":49373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[44],"tags":[],"class_list":{"0":"post-49372","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-example-6"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=49372"}],"version-history":[{"count":1,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49372\/revisions"}],"predecessor-version":[{"id":49374,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/49372\/revisions\/49374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/49373"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=49372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=49372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=49372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}