{"id":40384,"date":"2023-02-09T11:10:36","date_gmt":"2023-02-09T11:10:36","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/02\/09\/zelensky-participa-de-reuniao-da-uniao-europeia-em-bruxelas\/"},"modified":"2023-02-09T11:10:36","modified_gmt":"2023-02-09T11:10:36","slug":"zelensky-participa-de-reuniao-da-uniao-europeia-em-bruxelas","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/02\/09\/zelensky-participa-de-reuniao-da-uniao-europeia-em-bruxelas\/","title":{"rendered":"Zelensky participa de reuni\u00e3o da Uni\u00e3o Europeia em Bruxelas"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/s2.glbimg.com\/-g9ze4C330-Nwue4r3n84lenEUY=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2023\/G\/U\/D0VlXhQFK7zbXQU9hspA\/2023-02-09t100305z-1429766958-rc2k7z967m6u-rtrmadp-3-ukraine-crisis-eu-zelenskiy.jpg\"><br \/>     Durante viagem surpresa, presidente ucraniano foi at\u00e9 o Parlamento Europeu e discursou sobre o curso da guerra e as necessidades ucranianas. Presidente da Ucr\u00e2nia, Volodymyr Zelensky, \u00e9 recebido pela presidente do Parlamento Europeu, Roberta Metsola<br \/>\nPhilippe Buissin\/European Union 2023\/Handout via REUTERS<br \/>\nO presidente ucraniano, Volodymyr Zelensky, discursou nesta quinta-feira (9) em uma reuni\u00e3o do Parlamento Europeu, o bra\u00e7o legislativo da Uni\u00e3o Europeia, em viagem surpresa para Bruxelas. Quando chegou ao p\u00falpito, Zelensky foi ovacionado pelos legisladores da Uni\u00e3o Europeia.<br \/>\n&#8220;Estamos nos defendendo da maior for\u00e7a antieuropeia do mundo moderno&#8221;, disse Zelensky.<br \/>\nPresidente ucraniano, Volodymyr Zelensky, caminha ao lado da presidente do Parlamento Europeu, Roberta Metsola<br \/>\nAlexis Haulot\/Uni\u00e3o Europeia 2023\/Reprodu\u00e7\u00e3o via REUTERS<br \/>\nA chefe do Parlamento Europeu, Roberta Metsola, apoiou o pedido da Ucr\u00e2nia por mais armas.<br \/>\n\u201cSabemos o sacrif\u00edcio que seu povo suportou pela Europa e devemos honr\u00e1-lo n\u00e3o apenas com palavras, mas com a\u00e7\u00f5es\u201d, disse ela, acrescentando que isso deve incluir \u201cos jatos de que voc\u00ea precisa para proteger a liberdade que muitos consideram garantida\u201d, disse ela.<br \/>\nPosteriormente, Zelensky agradeceu os pa\u00edses que enviaram armamentos e disse que &#8220;a europa mant\u00e9m sua liberdade com a uni\u00e3o dos pa\u00edses&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante viagem surpresa, presidente ucraniano foi at\u00e9 o Parlamento Europeu e discursou sobre o curso da guerra e as necessidades ucranianas. Presidente da Ucr\u00e2nia, Volodymyr Zelensky, \u00e9 recebido pela presidente do Parlamento Europeu, Roberta Metsola Philippe Buissin\/European Union 2023\/Handout via REUTERS O presidente ucraniano, Volodymyr Zelensky, discursou nesta quinta-feira (9) em uma reuni\u00e3o do Parlamento<\/p>\n","protected":false},"author":1,"featured_media":40385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[47],"tags":[],"class_list":{"0":"post-40384","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mundo"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40384"}],"version-history":[{"count":0,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/40385"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}