{"id":40019,"date":"2023-02-08T09:12:43","date_gmt":"2023-02-08T09:12:43","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/02\/08\/confira-as-vagas-de-emprego-disponiveis-em-petrolina-salgueiro-e-araripina-nesta-quarta-feira-8\/"},"modified":"2023-02-08T09:12:43","modified_gmt":"2023-02-08T09:12:43","slug":"confira-as-vagas-de-emprego-disponiveis-em-petrolina-salgueiro-e-araripina-nesta-quarta-feira-8","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2023\/02\/08\/confira-as-vagas-de-emprego-disponiveis-em-petrolina-salgueiro-e-araripina-nesta-quarta-feira-8\/","title":{"rendered":"Confira as vagas de emprego dispon\u00edveis em Petrolina, Salgueiro e Araripina nesta quarta-feira (8)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/s2.glbimg.com\/Y0OlVDhFJCUg4naRzC--21jr1DY=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2022\/a\/P\/RmTjelSG26sHYqqSLgjw\/carteira-de-trabalho-foto-marcelo-camargo-abr.jpg\"><br \/>    As vagas s\u00e3o disponibilizadas diariamente pela Ag\u00eancia do Trabalho de Pernambuco. Carteira de Trabalho e Previd\u00eancia Social<br \/>\nMarcelo Camargo\/Ag\u00eancia Brasil<br \/>\nA Ag\u00eancia de Trabalho de Pernambuco divulgou as vagas de emprego disponibilizadas paras o munic\u00edpios de Petrolina, Salgueiro e Araripina, no Sert\u00e3o, nesta quarta-feira (8). As oportunidades s\u00e3o atualizadas diariamente pelo g1 Petrolina.<br \/>\nOs interessados nas oportunidades podem entrar em contato com a Seteq atrav\u00e9s da internet. O atendimento na Ag\u00eancia do Trabalho ocorre apenas com agendamento pr\u00e9vio, feito tanto pelo site da secretaria, quanto pelo Portal Cidad\u00e3o.<br \/>\nPetrolina<br \/>\nContato: (87) 3866 &#8211; 6540<br \/>\nVagas dispon\u00edveis<\/p>\n<p>Salgueiro<\/p>\n<p>Contato: (87) 3871 &#8211; 8467<br \/>\nVagas dispon\u00edveis<br \/>\nAraripina<br \/>\nContato: (87) 3873 &#8211; 8381<br \/>\nVagas dispon\u00edveis<br \/>\nV\u00eddeos: mais assistidos do Sert\u00e3o de PE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As vagas s\u00e3o disponibilizadas diariamente pela Ag\u00eancia do Trabalho de Pernambuco. Carteira de Trabalho e Previd\u00eancia Social Marcelo Camargo\/Ag\u00eancia Brasil A Ag\u00eancia de Trabalho de Pernambuco divulgou as vagas de emprego disponibilizadas paras o munic\u00edpios de Petrolina, Salgueiro e Araripina, no Sert\u00e3o, nesta quarta-feira (8). As oportunidades s\u00e3o atualizadas diariamente pelo g1 Petrolina. Os interessados<\/p>\n","protected":false},"author":1,"featured_media":40020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-40019","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40019"}],"version-history":[{"count":0,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/40020"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}