{"id":29821,"date":"2022-12-30T16:11:32","date_gmt":"2022-12-30T16:11:32","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2022\/12\/30\/quem-e-rita-serrano-indicada-por-haddad-para-assumir-presidencia-da-caixa\/"},"modified":"2022-12-30T16:11:32","modified_gmt":"2022-12-30T16:11:32","slug":"quem-e-rita-serrano-indicada-por-haddad-para-assumir-presidencia-da-caixa","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2022\/12\/30\/quem-e-rita-serrano-indicada-por-haddad-para-assumir-presidencia-da-caixa\/","title":{"rendered":"Quem \u00e9 Rita Serrano, indicada por Haddad para assumir presid\u00eancia da Caixa"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/s2.glbimg.com\/x6-dmnGA08pHWLhgad0W5gYLQVw=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2022\/O\/G\/4apk3BRfWNqJciqG0yxQ\/whatsapp-image-2022-12-30-at-11.54.37.jpeg\"><br \/>   Futura presidente \u00e9 funcion\u00e1ria do banco h\u00e1 mais de 30 anos, foi conselheira eleita pelos empregados e cobrou celeridade na apura\u00e7\u00e3o das den\u00fancias contra Pedro Guimar\u00e3es.  Rita Serrano, nova presidente da Caixa (de vermelho), e Tarciana Medeiros, nova presidente do BB, com o futuro ministro da Fazenda, Fernando Haddad.<br \/>\nPedro Henrique Gomes \/ g1<br \/>\nO futuro ministro da Fazenda do governo Lula, Fernando Haddad, anunciou nesta sexta-feira (30) que Rita Serrano ser\u00e1 a nova presidente da Caixa Econ\u00f4mica Federal.<br \/>\nSerrano \u00e9 funcion\u00e1ria da Caixa desde 1989, onde exerceu diversas fun\u00e7\u00f5es. Desde 2014, participa do Conselho de Administra\u00e7\u00e3o do banco. Primeiro, como suplente. E, desde 2017, como titular, com duas reelei\u00e7\u00f5es desde ent\u00e3o.<br \/>\nComo representante dos empregados, Serrano cobrou celeridade na apura\u00e7\u00e3o sobre as den\u00fancias de ass\u00e9dio sexual feitas contra o ex-presidente da Caixa, Pedro Guimar\u00e3es, em junho.<br \/>\nAtiva em \u00f3rg\u00e3os ligados \u00e0 estatal, ela ocupada o cargo de 3\u00aa conselheira na Federa\u00e7\u00e3o Nacional das Associa\u00e7\u00f5es do Pessoal da Caixa Econ\u00f4mica Federal (Fenae), que atua como entidade de defesa dos direitos dos empregados.<br \/>\nEla tamb\u00e9m presidiu o sindicato dos Banc\u00e1rios do ABC Paulista, entre 2006 e 2012. E coordena, desde 2015, o Comit\u00ea Nacional em Defesa das Empresas P\u00fablicas.<br \/>\nA futura presidente da caixa \u00e9 formada em estudos sociais e hist\u00f3ria, com mestrado em administra\u00e7\u00e3o pela Universidade Municipal de S\u00e3o Caetano do Sul.<br \/>\nTamb\u00e9m escreveu tr\u00eas livros: &#8220;O desenvolvimento socioecon\u00f4mico de Rio Grande da Serra&#8221; (2007), &#8220;Caixa, banco dos brasileiros&#8221; (2018) e &#8220;Rompendo barreiras&#8221; (2022).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Futura presidente \u00e9 funcion\u00e1ria do banco h\u00e1 mais de 30 anos, foi conselheira eleita pelos empregados e cobrou celeridade na apura\u00e7\u00e3o das den\u00fancias contra Pedro Guimar\u00e3es. Rita Serrano, nova presidente da Caixa (de vermelho), e Tarciana Medeiros, nova presidente do BB, com o futuro ministro da Fazenda, Fernando Haddad. Pedro Henrique Gomes \/ g1 O<\/p>\n","protected":false},"author":1,"featured_media":29822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":{"0":"post-29821","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29821"}],"version-history":[{"count":0,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/29822"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}