{"id":27063,"date":"2022-12-18T00:13:10","date_gmt":"2022-12-18T00:13:10","guid":{"rendered":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2022\/12\/18\/mega-sena-concurso-2-549-resultado\/"},"modified":"2022-12-18T00:13:10","modified_gmt":"2022-12-18T00:13:10","slug":"mega-sena-concurso-2-549-resultado","status":"publish","type":"post","link":"https:\/\/comandogeraldanoticia.com.br\/index.php\/2022\/12\/18\/mega-sena-concurso-2-549-resultado\/","title":{"rendered":"Mega-Sena, concurso 2.549: resultado"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/s2.glbimg.com\/JC6Olrj3y5Bw8noSiAj8fabOVT0=\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2019\/H\/i\/BjMFSLTd68zGX2TBtUag\/volantes-loterias-q98a7776-credito-marcelo-brandt-g1.jpg\"><br \/>   Confira os n\u00fameros sorteados:  01 &#8211; 06 &#8211; 10 &#8211; 30 &#8211; 33 &#8211; 35. Pr\u00eamio \u00e9 de R$ 4,5 milh\u00f5es Aposta \u00fanica da Mega-Sena custa R$ 4,50 e apostas podem ser feitas at\u00e9 as 19h<br \/>\nMarcelo Brandt\/G1<br \/>\nOs n\u00fameros do sorteio 2.549 da Mega-Sena foram sorteados neste s\u00e1bado (17), em S\u00e3o Paulo. Este sorteio pode pagar R$ 4,5 milh\u00f5es para a aposta que acertar as seis dezenas.(Confira mais abaixo os maiores pr\u00eamios j\u00e1 pagos pela Mega-Sena.)<br \/>\nVeja as dezenas sorteadas: 01 &#8211; 06 &#8211; 10 &#8211; 30 &#8211; 33 &#8211; 35.<br \/>\nAt\u00e9 as 20h25, o rateio ainda n\u00e3o havia sido divulgado pela Caixa Econ\u00f4mica Federal.<br \/>\nMega-Sena, concurso 2.549<br \/>\nReprodu\u00e7\u00e3o<br \/>\nMaiores pr\u00eamios<br \/>\nO maior pr\u00eamio deste ano \u2013 tamb\u00e9m o maior valor da hist\u00f3ria, sem contar a Mega da Virada \u2013 foi de R$ 317.853.788,54, pago em 1\u00ba de outubro.<br \/>\nQuando considerados os maiores pr\u00eamios da Mega desde 2013, o desta quarta-feira \u00e9 o oitavo maior da hist\u00f3ria\u2013 atr\u00e1s do sorteio de 22 de novembro de 2014, que pagou R$ 135.315.118,96.<br \/>\nPara apostar na Mega-Sena<br \/>\nAs apostas podem ser feitas at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia), em qualquer lot\u00e9rica do pa\u00eds ou pela internet, no site da Caixa Econ\u00f4mica Federal \u2013 acess\u00edvel por celular, computador ou outros dispositivos. \u00c9 necess\u00e1rio fazer um cadastro, ser maior de idade (18 anos ou mais) e preencher o n\u00famero do cart\u00e3o de cr\u00e9dito.<br \/>\nEntenda como funciona a Mega-Sena e qual a probabilidade de ganhar o pr\u00eamio<br \/>\nProbabilidades<br \/>\nA probabilidade de vencer em cada concurso varia de acordo com o n\u00famero de dezenas jogadas e do tipo de aposta realizada. Para a aposta simples, com apenas seis dezenas, com pre\u00e7o de R$ 4,50, a probabilidade de ganhar o pr\u00eamio milion\u00e1rio \u00e9 de 1 em 50.063.860, segundo a Caixa.<br \/>\nJ\u00e1 para uma aposta com 15 dezenas (limite m\u00e1ximo), com o pre\u00e7o de R$ 22.522,50, a probabilidade de acertar o pr\u00eamio \u00e9 de 1 em 10.003, ainda segundo a Caixa.<br \/>\nInitial plugin text<br \/>\nV\u00cdDEOS: mais assistidos do G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira os n\u00fameros sorteados: 01 &#8211; 06 &#8211; 10 &#8211; 30 &#8211; 33 &#8211; 35. Pr\u00eamio \u00e9 de R$ 4,5 milh\u00f5es Aposta \u00fanica da Mega-Sena custa R$ 4,50 e apostas podem ser feitas at\u00e9 as 19h Marcelo Brandt\/G1 Os n\u00fameros do sorteio 2.549 da Mega-Sena foram sorteados neste s\u00e1bado (17), em S\u00e3o Paulo. Este sorteio<\/p>\n","protected":false},"author":1,"featured_media":27064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[50],"tags":[],"class_list":{"0":"post-27063","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-loteria"},"_links":{"self":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27063"}],"version-history":[{"count":0,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media\/27064"}],"wp:attachment":[{"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comandogeraldanoticia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}